{"id":101,"date":"2018-10-12T09:45:15","date_gmt":"2018-10-12T09:45:15","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/"},"modified":"2018-10-12T09:45:15","modified_gmt":"2018-10-12T09:45:15","slug":"elections-accder-lespace-lecteur-et-crer-son-mot-de-passe","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/","title":{"rendered":"Elections : Acc\u00e9der \u00e0 l&rsquo;espace \u00e9lecteur et cr\u00e9er son mot de passe"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png\" alt=\"\" align=\"right\" width=\"959\" height=\"405\" class=\"spip_logos\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9lections ont lieu du 29 novembre au 6 d\u00e9cembre. L&rsquo;espace \u00e9lecteur, ouvert depuis ce jeudi 11 octobre, permet de cr\u00e9er son mot de passe, de v\u00e9rifier les scrutins auxquels j&rsquo;aurai acc\u00e8s, de v\u00e9rifier les listes \u00e9lectorales de mes scrutins. La FSU vous aide pour cela !<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique316\" rel=\"directory\">Elections professionnelles 2018<\/a><br \/>\n\/<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?mot287\" rel=\"tag\">\u00e9lections<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-101","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elections : Acc\u00e9der \u00e0 l&#039;espace \u00e9lecteur et cr\u00e9er son mot de passe - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elections : Acc\u00e9der \u00e0 l&#039;espace \u00e9lecteur et cr\u00e9er son mot de passe - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9lections ont lieu du 29 novembre au 6 d\u00e9cembre. L&#039;espace \u00e9lecteur, ouvert depuis ce jeudi 11 octobre, permet de cr\u00e9er son mot de passe, de v\u00e9rifier les scrutins auxquels j&#039;aurai acc\u00e8s, de v\u00e9rifier les listes \u00e9lectorales de mes scrutins. La FSU vous aide pour cela ! - Elections professionnelles 2018 \/ \u00e9lections\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-12T09:45:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/\",\"name\":\"Elections : Acc\u00e9der \u00e0 l'espace \u00e9lecteur et cr\u00e9er son mot de passe - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png\",\"datePublished\":\"2018-10-12T09:45:15+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elections : Acc\u00e9der \u00e0 l&#8217;espace \u00e9lecteur et cr\u00e9er son mot de passe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elections : Acc\u00e9der \u00e0 l'espace \u00e9lecteur et cr\u00e9er son mot de passe - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/","og_locale":"fr_FR","og_type":"article","og_title":"Elections : Acc\u00e9der \u00e0 l'espace \u00e9lecteur et cr\u00e9er son mot de passe - FSU-SNUipp 86","og_description":"Les \u00e9lections ont lieu du 29 novembre au 6 d\u00e9cembre. L'espace \u00e9lecteur, ouvert depuis ce jeudi 11 octobre, permet de cr\u00e9er son mot de passe, de v\u00e9rifier les scrutins auxquels j'aurai acc\u00e8s, de v\u00e9rifier les listes \u00e9lectorales de mes scrutins. La FSU vous aide pour cela ! - Elections professionnelles 2018 \/ \u00e9lections","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-10-12T09:45:15+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/","name":"Elections : Acc\u00e9der \u00e0 l'espace \u00e9lecteur et cr\u00e9er son mot de passe - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png","datePublished":"2018-10-12T09:45:15+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4128.png"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/10\/12\/elections-accder-lespace-lecteur-et-crer-son-mot-de-passe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Elections : Acc\u00e9der \u00e0 l&#8217;espace \u00e9lecteur et cr\u00e9er son mot de passe"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=101"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/101\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}