{"id":118,"date":"2018-08-28T08:31:58","date_gmt":"2018-08-28T08:31:58","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/"},"modified":"2018-08-28T08:31:58","modified_gmt":"2018-08-28T08:31:58","slug":"audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/","title":{"rendered":"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg\" alt=\"\" align=\"right\" width=\"1020\" height=\"573\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">Le SNUipp-FSU 86 a eu une courte audience (30 min) \u00e0 la mairie de Poitiers avec Laurence VALLOIS-ROUET, 1\u00e8re adjointe d\u00e9l\u00e9gu\u00e9e \u00e0 l&rsquo;\u00e9ducation, ce lundi 27 ao\u00fbt.<\/p>\n<dl class='spip_document_3668 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/jpg\/58c3336c469a455c008b5f9c.jpg' width='520' height='293' alt='JPEG - 56.9 ko' style='height:293px;width:520px;' class='' \/><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>58c3336c469a455c008b5f9c<\/strong><\/dt>\n<\/dl>\n<p class=\"spip\">Nous avons pu aborder les sujets suivants :<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_0\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Projets d&rsquo; \u00ab\u00a0offre scolaire\u00a0\u00bb sur Poitiers : nombre d&rsquo;\u00e9coles, r\u00e9novation ou construction de b\u00e2timents &#8230;<\/h3>\n<p class=\"spip\">Mme Vallois-Rouet a indiqu\u00e9 qu&rsquo;un certain nombre de projets \u00e9taient en cours ou allaient \u00eatre lanc\u00e9s :<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Quartier de Bellejouanne<\/strong> : fusion des \u00e9coles P\u00e9rochon et Pagnol. 2 options sont toujours en cours : la construction d&rsquo;une nouvelle \u00e9cole ou la r\u00e9habilitation et l&rsquo;agrandissement des \u00e9coles de Pagnol. Si les services techniques de la ville de Poitiers pr\u00e9f\u00e9reraient la 1\u00e8re solution, plus simple \u00e0 mettre en \u0153uvre, l&rsquo;adjointe pr\u00e9f\u00e9rerait la 2nde car elle permettrait de conserver l&rsquo;\u00e9cole \u00e0 proximit\u00e9 de CAP Sud, de la biblioth\u00e8que, de la piscine, des commerces &#8230; et de pr\u00e9server des espaces verts.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Quartier de Montmidi<\/strong> : la maternelle doit \u00eatre reconstruite du fait de sa v\u00e9tust\u00e9 et pour permettre d&rsquo;augmenter la capacit\u00e9 d&rsquo;accueil. Le terrain des Montgorges sera la destination de la nouvelle \u00e9cole, ainsi que pour la cantine. La r\u00e9flexion est en cours pour savoir si l&rsquo;\u00e9cole \u00e9l\u00e9mentaire sera r\u00e9nov\u00e9e ou reconstruite en fonction du budget.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Quartier d&rsquo;Aboville<\/strong> : une nouvelle \u00e9cole plac\u00e9e au \u00a0\u00bb Parc \u00e0 Fourrage \u00a0\u00bb pourrait voir le jour et rassemblerait l&rsquo;\u00e9l\u00e9mentaire Coligny-Cornet et la maternelle Pasteur. L&rsquo;\u00e9cole Petit-Tour ne serait pas concern\u00e9e. La mairie explique que ce transfert serait une grande \u00e9conomie budg\u00e9taire notamment en terme d&rsquo;entretien et r\u00e9soudrait les probl\u00e9matiques li\u00e9es au respect des travaux dans une zone de protection du patrimoine.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Centre Ville<\/strong> : la marie souhaite r\u00e9unir les 2 sites de l&rsquo;\u00e9cole \u00e9l\u00e9mentaire Damien Allard-Ferry sur un m\u00eame lieu et se servir du site d\u00e9gag\u00e9 pour y transf\u00e9rer la maternelle Renaudot.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Ecoles en \u00e9ducation prioritaire<\/strong> : le SNUipp-FSU a indiqu\u00e9 son inqui\u00e9tude pour la rentr\u00e9e 2019 et le d\u00e9doublement des classes en CE1 en REP. En effet, dans beaucoup d&rsquo;\u00e9coles, le d\u00e9doublement des classes en CP a d\u00e9j\u00e0 \u00ab\u00a0amput\u00e9\u00a0\u00bb les \u00e9coles de nombreuses salles (arts plastiques, r\u00e9unions, rased &#8230;). La mairie ne sait pas encore comment elle fera face \u00e0 cette probl\u00e9matique et Mme Vallois-Rouet \u00e9voque les \u00a0\u00bb fameuses \u00a0\u00bb cloisons pour couper les salles&#8230; De mani\u00e8re g\u00e9n\u00e9rale, le SNUipp-FSU a indiqu\u00e9 que certain-es coll\u00e8gues en \u00e9ducation prioritaire s&rsquo;inqui\u00e9taient de voir leurs \u00e9coles chaque ann\u00e9e avec des effectifs de plus en plus important ( jusqu&rsquo;\u00e0 + de 300 \u00e9l\u00e8ves aux Couronneries ) et trouvaient que l&rsquo;on travaillait de fa\u00e7on plus efficace dans des structures plus \u00a0\u00bb petites \u00a0\u00bb qui permettent par exemple de mieux accompagner les familles. L&rsquo;adjointe a sembl\u00e9 \u00eatre en accord avec cette position.<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_1\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Scolarisation des moins de 3 ans<\/h3>\n<p class=\"spip\">Le SNUipp-FSU est intervenu sur les scolarisations de \u00a0\u00bb moins de 3 ans \u00a0\u00bb impos\u00e9es aux \u00e9coles en cours d&rsquo;ann\u00e9e, malgr\u00e9 des effectifs importants. L&rsquo;adjointe a reconnu que cela pouvait avoir lieu suite aux vacances de la Toussaint car elle \u00e9tait dans l&rsquo;obligation l\u00e9gale de scolariser des \u00e9l\u00e8ves de \u00ab\u00a0moins de 3 ans\u00a0\u00bb qui arrivaient sur la ville suite \u00e0 un d\u00e9m\u00e9nagement et qui \u00e9taient pr\u00e9c\u00e9demment scolaris\u00e9s. Elle indique que le manque de places pour les \u00a0\u00bb moins de 3 ans \u00a0\u00bb sur Beaulieu (Licorne et Brassens) la mettait en difficult\u00e9. Elle soutient aussi la mise en place du dispositif sur Brel pour la rentr\u00e9e 2019.<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_2\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Future carte \u00e9ducation prioritaire<\/h3>\n<p class=\"spip\">Une nouvelle carte \u00e9ducation prioritaire doit \u00eatre d\u00e9voil\u00e9e en cette fin d&rsquo;ann\u00e9e pour \u00eatre appliqu\u00e9e \u00e0 la rentr\u00e9e prochaine. Le SNUipp-FSU a demand\u00e9 \u00e0 la mairie de tenir la m\u00eame position que notre syndicat : regarder la situation des \u00e9coles, sans tenir compte du classement du coll\u00e8ge, pour demander au recteur et \u00e0 l&rsquo;IA le classement ad\u00e9quat en \u00e9ducation prioritaire. L&rsquo;adjointe a approuv\u00e9 cette position et rappel\u00e9 son engagement pour la conservation du classement \u00e9ducation prioritaire pour Charles Perrault, malgr\u00e9 son rattachement au coll\u00e8ge du Jardin des Plantes. Dans ce cadre d&rsquo; \u00ab\u00a0\u00e9coles isol\u00e9es\u00a0\u00bb, c&rsquo;est \u00e0 dire n&rsquo;\u00e9tant pas rattach\u00e9es \u00e0 un coll\u00e8ge \u00e9ducation prioritaire mais pr\u00e9sentant un public avec certaines sp\u00e9cificit\u00e9s, les quartiers de St Eloi, Beaulieu ou Bel Air ont \u00e9t\u00e9 \u00e9voqu\u00e9s par l&rsquo;adjointe.<\/p>\n<p class=\"spip\">Le SNUipp-FSU a rappel\u00e9 \u00e0 l&rsquo;adjointe que la premi\u00e8re priorit\u00e9 devait \u00eatre l&rsquo;am\u00e9lioration de la politique de logement et de mixit\u00e9 sociale sur Poitiers. L&rsquo;adjointe a indiqu\u00e9 qu&rsquo;elle \u00e9tait en accord avec nous, que cela \u00e9tait une priorit\u00e9 depuis 2009 de la mairie. Une commission doit d&rsquo;ailleurs \u00eatre mise en place \u00e0 cette rentr\u00e9e pour travailler avec les bailleurs sociaux sur le sujet.<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_3\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Autres sujets \u00e9voqu\u00e9s<\/h3>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">scolarisation des \u00e9l\u00e8ves allophones<\/strong> : le SNUipp-FSU a indiqu\u00e9 qu&rsquo;il \u00e9tait important que les \u00e9l\u00e8ves ne soient pas scolaris\u00e9s dans les m\u00eames \u00e9coles mais que la mairie aide \u00e0 l&rsquo;organisation et au financement des temps de rassemblements avec les enseignant-es UPE2A<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">rythmes scolaires<\/strong> : la mairie ne souhaite effectuer aucune modification sur l&rsquo;organisation des rythmes scolaires de la ville. Le SNUipp-FSU a indiqu\u00e9 que les enseignant-es voudraient une organisation qui permette de lib\u00e9rer du temps pour effectuer leurs nombreuses r\u00e9unions parmi les 9 demi-journ\u00e9es et que dans ce cadre, nous continuions \u00e0 demander nationalement la possibilit\u00e9 de travailler avec 1 mercredi sur 3 sans \u00e9l\u00e8ve comme cela \u00e9tait le cas avant 2013.<\/p>\n<p class=\"spip\">Merci aux coll\u00e8gues qui nous ont part de leurs questionnements pour pr\u00e9parer cette audience.<\/p>\n<p class=\"spip\">Bonne pr\u00e9paration de rentr\u00e9e<\/p>\n<p class=\"spip\">pour le SNUipp-FSU 86, Matthieu MENAUT-LOURTAS et Fabienne LAINE<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le SNUipp-FSU 86 a eu une courte audience (30 min) \u00e0 la mairie de Poitiers avec Laurence VALLOIS-ROUET, 1\u00e8re adjointe d\u00e9l\u00e9gu\u00e9e \u00e0 l&rsquo;\u00e9ducation, ce lundi 27 ao\u00fbt. <br \/>Nous avons pu aborder les sujets suivants : <br \/>Projets d&rsquo; \u00ab\u00a0offre scolaire\u00a0\u00bb sur Poitiers : nombre d&rsquo;\u00e9coles, r\u00e9novation ou construction de b\u00e2timents &#8230; <br \/>Mme Vallois-Rouet a indiqu\u00e9 qu&rsquo;un certain nombre de projets \u00e9taient en cours ou allaient \u00eatre lanc\u00e9s : <br \/>Quartier de Bellejouanne : fusion des \u00e9coles P\u00e9rochon et Pagnol. 2 options (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique249\" rel=\"directory\">L&rsquo;ACTUALIT\u00c9<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-118","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Le SNUipp-FSU 86 a eu une courte audience (30 min) \u00e0 la mairie de Poitiers avec Laurence VALLOIS-ROUET, 1\u00e8re adjointe d\u00e9l\u00e9gu\u00e9e \u00e0 l&#039;\u00e9ducation, ce lundi 27 ao\u00fbt. Nous avons pu aborder les sujets suivants : Projets d&#039; &quot;offre scolaire&quot; sur Poitiers : nombre d&#039;\u00e9coles, r\u00e9novation ou construction de b\u00e2timents ... Mme Vallois-Rouet a indiqu\u00e9 qu&#039;un certain nombre de projets \u00e9taient en cours ou allaient \u00eatre lanc\u00e9s : Quartier de Bellejouanne : fusion des \u00e9coles P\u00e9rochon et Pagnol. 2 options (...) - L&#039;ACTUALIT\u00c9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-28T08:31:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/\",\"name\":\"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg\",\"datePublished\":\"2018-08-28T08:31:58+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/","og_locale":"fr_FR","og_type":"article","og_title":"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU - FSU-SNUipp 86","og_description":"Le SNUipp-FSU 86 a eu une courte audience (30 min) \u00e0 la mairie de Poitiers avec Laurence VALLOIS-ROUET, 1\u00e8re adjointe d\u00e9l\u00e9gu\u00e9e \u00e0 l'\u00e9ducation, ce lundi 27 ao\u00fbt. Nous avons pu aborder les sujets suivants : Projets d' \"offre scolaire\" sur Poitiers : nombre d'\u00e9coles, r\u00e9novation ou construction de b\u00e2timents ... Mme Vallois-Rouet a indiqu\u00e9 qu'un certain nombre de projets \u00e9taient en cours ou allaient \u00eatre lanc\u00e9s : Quartier de Bellejouanne : fusion des \u00e9coles P\u00e9rochon et Pagnol. 2 options (...) - L'ACTUALIT\u00c9","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-08-28T08:31:58+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/","name":"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg","datePublished":"2018-08-28T08:31:58+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4064.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/28\/audience-mairie-de-poitiers-du-27-8-18-compte-rendu-snuipp-fsu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Audience mairie de Poitiers du 27\/8\/18 : compte rendu SNUipp-FSU"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/118\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}