{"id":120,"date":"2018-08-24T06:41:16","date_gmt":"2018-08-24T06:41:16","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/"},"modified":"2018-08-24T06:41:16","modified_gmt":"2018-08-24T06:41:16","slug":"direction-et-fonctionnement-dcole-8-pages-snuipp-fsu","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/","title":{"rendered":"Direction et fonctionnement d&rsquo;\u00e9cole : 8 pages SNUipp-FSU"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg\" alt=\"\" align=\"right\" width=\"647\" height=\"913\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">Retrouvez le dernier 8 pages sp\u00e9cial Direction .<\/p>\n<p class=\"spip\">Au programme, des infos administratives ( d\u00e9charges, indemnit\u00e9s &#8230;) et des dossiers ( le statut, les \u00e9l\u00e8ves \u00e0 besoins particuliers &#8230;).<\/p>\n<p class=\"spip\">Bonne lecture<\/p>\n<dl class='spip_document_3664 spip_documents spip_documents_center' >\n<dt><a href=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/pdf\/snuipp-direction-2018-hd.pdf\" class=\"spip_out\" title='JPEG - 124.5 ko'><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/jpg\/arton4252.jpg' width='520' height='734' alt='JPEG - 124.5 ko' style='height:734px;width:520px;' class='' \/><\/a><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>arton4252<\/strong><\/dt>\n<\/dl>\n<dl class='spip_document_3662 spip_documents spip_documents_center' >\n<dt><a href=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/pdf\/snuipp-direction-2018-hd.pdf\" title='PDF - 3.1 Mo' type=\"application\/pdf\"><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L52xH52\/pdf-d7486.png' width='52' height='52' alt='PDF - 3.1 Mo' style='height:52px;width:52px;' class=' format_png' \/><\/a><\/dt>\n<dt class='spip_doc_titre' style='width:120px;'><strong>snuipp-direction-2018-hd<\/strong><\/dt>\n<\/dl>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le dernier 8 pages sp\u00e9cial Direction . <br \/>Au programme, des infos administratives ( d\u00e9charges, indemnit\u00e9s &#8230;) et des dossiers ( le statut, les \u00e9l\u00e8ves \u00e0 besoins particuliers &#8230;). <br \/>Bonne lecture <br \/>https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/pdf\/snuipp-&#8230;<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique296\" rel=\"directory\">Directions d&rsquo;\u00e9coles<\/a><br \/>\n\/<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?mot303\" rel=\"tag\">Directions d&rsquo;\u00e9coles<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-120","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Direction et fonctionnement d&#039;\u00e9cole : 8 pages SNUipp-FSU - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Direction et fonctionnement d&#039;\u00e9cole : 8 pages SNUipp-FSU - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le dernier 8 pages sp\u00e9cial Direction . Au programme, des infos administratives ( d\u00e9charges, indemnit\u00e9s ...) et des dossiers ( le statut, les \u00e9l\u00e8ves \u00e0 besoins particuliers ...). Bonne lecture http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/pdf\/snuipp-... - Directions d&#039;\u00e9coles \/ Directions d&#039;\u00e9coles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-24T06:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/\",\"name\":\"Direction et fonctionnement d'\u00e9cole : 8 pages SNUipp-FSU - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg\",\"datePublished\":\"2018-08-24T06:41:16+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Direction et fonctionnement d&#8217;\u00e9cole : 8 pages SNUipp-FSU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Direction et fonctionnement d'\u00e9cole : 8 pages SNUipp-FSU - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/","og_locale":"fr_FR","og_type":"article","og_title":"Direction et fonctionnement d'\u00e9cole : 8 pages SNUipp-FSU - FSU-SNUipp 86","og_description":"Retrouvez le dernier 8 pages sp\u00e9cial Direction . Au programme, des infos administratives ( d\u00e9charges, indemnit\u00e9s ...) et des dossiers ( le statut, les \u00e9l\u00e8ves \u00e0 besoins particuliers ...). Bonne lecture http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/pdf\/snuipp-... - Directions d'\u00e9coles \/ Directions d'\u00e9coles","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-08-24T06:41:16+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/","name":"Direction et fonctionnement d'\u00e9cole : 8 pages SNUipp-FSU - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg","datePublished":"2018-08-24T06:41:16+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4056.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/08\/24\/direction-et-fonctionnement-dcole-8-pages-snuipp-fsu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Direction et fonctionnement d&#8217;\u00e9cole : 8 pages SNUipp-FSU"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/120\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}