{"id":142,"date":"2018-06-14T15:08:48","date_gmt":"2018-06-14T15:08:48","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/"},"modified":"2018-06-14T15:08:48","modified_gmt":"2018-06-14T15:08:48","slug":"ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/","title":{"rendered":"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A &#8230;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png\" alt=\"\" align=\"right\" width=\"120\" height=\"93\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<h3 class=\"spip\" id=\"outil_sommaire_0\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>CTSD du 11 juin<\/h3>\n<p class=\"spip\">Retrouvez ci-dessous le compte rendu complet du CTSD o\u00f9 l&rsquo;IA a prononc\u00e9 les d\u00e9cisions d&rsquo;ouvertures et fermetures de ce lien :<a href=\"http:\/\/86.snuipp.fr\/spip.php?article3974&#038;var_mode=calcul\" class=\"spip_out\">http:\/\/86.snuipp.fr\/spip.php ?article3974<\/a><\/p>\n<dl class='spip_document_3490 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L120xH93\/ctsd-4-54ebb.png' width='120' height='93' alt='PNG - 18.4 ko' style='height:93px;width:120px;' class=' format_png' \/><\/dt>\n<dt class='spip_doc_titre' style='width:120px;'><strong>ctsd<\/strong><\/dt>\n<\/dl>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> 1- D\u00e9claration liminaire : \ufeffprotocole ruralit\u00e9, UPE2A, IEN\ufeff<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> 2- D\u00e9cisions d&rsquo;ouvertures et fermetures : explications, vote, la suite<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> 3- Questions diverses : 1er degr\u00e9 en coll\u00e8ge, ULIS, EREA, contactuel-le-s, moins de 3 ans<\/p>\n<p class=\"spip\"><strong class=\"spip\">Pr\u00e9sent-e-s<\/strong> : M. Claverie ( IA ) , M. Monlun ( SG) , M. Artaud (IENA), 5 IEN ( ASH, Montmorillon, Poitiers Est, Poitiers Ouest, Poitiers Sud) , 2 DOSES ( Mme Lienart, Mme Librero), <strong class=\"spip\">7 FSU \/ CGT<\/strong> , 4 SE-Unsa, 2 FO, 1 Snalc<\/p>\n<p class=\"spip\">Le SNUipp si\u00e8ge au sein de la d\u00e9l\u00e9gation FSU \/ CGT.<\/p>\n<dl class='spip_document_3492 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/jpg\/logo-fsu-cgt.jpg' width='520' height='346' alt='JPEG - 122.1 ko' style='height:346px;width:520px;' class='' \/><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>logo-fsu-cgt<\/strong><\/dt>\n<\/dl>\n<p class=\"spip\"><strong class=\"spip\">Note d&rsquo;ambiance :<\/strong> Lors du groupe de travail du 7 juin , la FSU \/CGT n&rsquo;avait obtenu que quelques r\u00e9ponses sur les situations d&rsquo;\u00e9coles car les IEN \u00e9taient absent-e-s, la FSU \/ CGT a donc port\u00e9 \u00e0 nouveau toutes les situations lors de ce CTSD ! Quelques d\u00e9l\u00e9gations de parents \u00e9taient pr\u00e9sentes pour manifester contre les projets de l&rsquo;IA : Dissay mat, Vouill\u00e9 mat, Chir\u00e9 en Montreuil &#8230; Les d\u00e9l\u00e9gations ont \u00e9t\u00e9 re\u00e7ues par l&rsquo;IENA et les IEN concern\u00e9-es au cours du CTSD.<\/p>\n<hr class=\"spip\" \/>\n<h3 class=\"spip\" id=\"outil_sommaire_1\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>D\u00e9claration liminaire : protocole ruralit\u00e9, UPE2A, IEN<\/h3>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">D\u00e9claration FSU \/ CGT : absence IEN, protocole ruralit\u00e9<\/strong><\/p>\n<p class=\"spip\">Lors de sa d\u00e9claration liminaire, la FSU \/ CGT est revenue sur la probl\u00e9matique li\u00e9e \u00e0 l&rsquo;absence des IEN lors du GT. L&rsquo;IA a indiqu\u00e9 que tou-te-s les IEN \u00e9taient mobilis\u00e9-e-s par le CRPE , mais que les infos remont\u00e9es en groupe de travail avaient \u00e9t\u00e9 travaill\u00e9es depuis avec eux\/elles.<\/p>\n<p class=\"spip\"><strong class=\"spip\">La FSU\/CGT a aussi d\u00e9nonc\u00e9 la nouvelle interpr\u00e9tation des termes des accords du protocole ruralit\u00e9 fait par l&rsquo;IA sur Civray<\/strong>. L&rsquo;IA justifie sa d\u00e9cision de ne pas maintenir le nombre total de postes impact\u00e9s dans la restructuration ( 9 postes transform\u00e9s 6 postes ) car il aurait \u00e9t\u00e9 cl\u00e9ment depuis 3 ans avec ces \u00e9coles sans effectuer de multiples fermetures.<\/p>\n<p class=\"spip\">La FSU \/ CGT a d\u00e9nonc\u00e9 cela.<\/p>\n<p class=\"spip\"><strong class=\"spip\">Premi\u00e8rement, l&rsquo;inspection avait parl\u00e9 de plus-value p\u00e9dagogique sur Civray, il n&rsquo;en est rien !<\/strong> Pas de baisse d&rsquo;effectifs par rapport \u00e0 l&rsquo;existant, pas de classes en plus en \u00e9l\u00e9mentaire pour l&rsquo;inclusion, pas de dispositif \u00ab\u00a0plus de maitres que de classes\u00a0\u00bb comme \u00e0 Charroux, plus de travail pour le coll\u00e8gue en charge de la direction (sans moyen de d\u00e9charge suppl\u00e9mentaire) &#8230; l&rsquo;IA a indiqu\u00e9 que les enseignant-es ressentiraient la plus-value sur le long terme avec la mutualisation des moyens des mairies par exemple.<\/p>\n<p class=\"spip\"><strong class=\"spip\">Deuxi\u00e8mement, l&rsquo;Education Nationale ne respecte pas ses engagements dans le cadre du protocole ruralit\u00e9<\/strong> (<a href=\"http:\/\/cache.media.education.gouv.fr\/file\/Mediatheque\/31\/6\/20170310_Convention_Ruralite_Vienne_2017-2020_Presse_735316.pdf\" class=\"spip_out\">lien<\/a>) : \u00a0\u00bb S\u00e9curisation des emplois l&rsquo;ann\u00e9e N o\u00f9 s&rsquo;op\u00e8re la reconfiguration effective du r\u00e9seau scolaire sur le territoire engag\u00e9 (commune, groupe de communes&#8230;) \u00a0\u00bb . Pour la FSU\/CGT, si l&rsquo;Education Nationale ne respecte pas ses engagements \u00e9crits, les autres signataires de l&rsquo;accord (pr\u00e9fecture , d\u00e9partement , association des maires ) n&rsquo;ont donc plus d&rsquo;obligation.<\/p>\n<dl class='spip_document_3494 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/jpg\/convention_rurale.jpg' width='520' height='348' alt='JPEG - 2.1 Mo' style='height:348px;width:520px;' class='' \/><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>convention rurale<\/strong><\/dt>\n<\/dl>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">D\u00e9claration commune intersyndicale sur les UPE2A<\/strong><\/p>\n<p class=\"spip\">En plus de leur d\u00e9claration liminaire respective, l&rsquo;ensemble des organisations syndicales a effectu\u00e9 une d\u00e9claration liminaire commune sur la situation des dispositifs UPE2A ( dispositifs avec enseignant-e-s sp\u00e9cialis\u00e9-e-s pour les \u00e9l\u00e8ves primo-arrivants ou allophones) et demand\u00e9 en urgence un poste suppl\u00e9mentaire sur le Grand Poitiers. L&rsquo;IA a indiqu\u00e9 son manque de moyens mais il partage le constat. Il souhaite dans l&rsquo;avenir que les UPE2A dans le 2nd degr\u00e9, interviennent aussi dans le 1er degr\u00e9. La FSU\/CGT lui a rappel\u00e9 que les 3 demi-postes suppl\u00e9mentaires qui vont ouvrir dans le 2nd degr\u00e9 \u00e0 la rentr\u00e9e ( Loudun, Ch\u00e2tellerault et sur les lyc\u00e9es pro de Poitiers) ont d\u00e9j\u00e0 une d\u00e9finition d&rsquo; \u00ab\u00a0UPE2A itin\u00e9rante\u00a0\u00bb mais elles ne r\u00e9pondront pas \u00e0 l&rsquo;urgence de Poitiers sur le 1er degr\u00e9. L&rsquo;IA envisage pour r\u00e9pondre \u00e0 cela, de demander \u00e0 la coll\u00e8gue sur Sommi\u00e8res du Clain d&rsquo;intervenir sur le Grand Poitiers sous r\u00e9serve de la modification de sa fiche de poste. Pour la FSU\/CGT, cette r\u00e9ponse n&rsquo;est pas la bonne et restera insuffisante.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">D\u00e9claration IEN<\/strong><\/p>\n<p class=\"spip\">Fait rare, M. Bonnet au nom des IEN en tant que doyen et en soutien \u00e0 leur coll\u00e8gue, a effectu\u00e9 une d\u00e9claration pour d\u00e9noncer les termes utilis\u00e9s lors d&rsquo;un envoi \u00e0 toute la profession, notamment la qualification d \u00ab\u00a0arbitraires \u00a0\u00bb sur les d\u00e9cisions prononc\u00e9es par une IEN.<\/p>\n<hr class=\"spip\" \/>\n<h3 class=\"spip\" id=\"outil_sommaire_2\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>D\u00e9cisions d&rsquo;ouvertures et fermetures<\/h3>\n<p class=\"spip\">Suite au groupe de travail de jeudi, l&rsquo;IA d\u00e9cide :<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> l<strong class=\"spip\">&lsquo;annulation de la fermeture prononc\u00e9e en mars sur Chauvigny les Guiraudi\u00e8res<\/strong> le fait que l&rsquo;\u00e9cole priv\u00e9e, en face de l&rsquo;\u00e9cole, disposera d&rsquo;une nouvelle classe \u00e0 la rentr\u00e9e 2018 semble avoir fait basculer la d\u00e9cision de l&rsquo;IA l&rsquo;annulation de la fermeture prononc\u00e9e en mars sur St L\u00e9ger de Montbrillais &#8211; l&rsquo;IA indique que sa d\u00e9cision fait suite au projet de restructuration pour l&rsquo;ann\u00e9e 2019 et non \u00e0 la pr\u00e9sence du d\u00e9put\u00e9 qui accompagnait la d\u00e9l\u00e9gation<br \/>\nl&rsquo;annulation de la fermeture prononc\u00e9e en mars sur S\u00e9rigny-Sossais &#8211; l&rsquo;IA indique que sa d\u00e9cision fait suite au projet de restructuration pour l&rsquo;ann\u00e9e 2019<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">l&rsquo;annulation du projet de fermeture sur Poitiers Microm\u00e9gas mat<\/strong> \u2013 la mairie de Poitiers aurait oubli\u00e9 de transmettre l&rsquo;inscription de presque 30 \u00e9l\u00e8ves suite \u00e0 l&rsquo;harmonisation sur e quartier \u2026 Concernant ce quartier, l&rsquo;IA demande une r\u00e9elle politique d&rsquo;affectation par la ville de Poitiers entre les \u00e9coles de N\u00e9ruda, Microm\u00e9gas, Breuil Mingot.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">l&rsquo;annulation du projet de fermeture sur Le Vigeant prim<\/strong> \u2013 aucun RPI n&rsquo;existe, cela ferait 28 ou 29 \u00e9l\u00e8ves \u00e0 la rentr\u00e9e sur une classe unique (25 \u00e9taient annonc\u00e9s). L&rsquo;IA demande que pour la rentr\u00e9e 2019 , une restructuration ait lieu avec les communes autour.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">l&rsquo;annulation du projet de fermetures sur Neuville les petits cailloux mat<\/strong> &#8211; l&rsquo;IA apr\u00e8s avoir expliqu\u00e9 qu&rsquo;il y avait des probl\u00e9matiques de r\u00e9partition entre les 2 \u00e9coles, a annul\u00e9 son projet de fermeture mais sans d\u00e9velopper d&rsquo;argumentaires alors que d&rsquo;autres situations de maternelle avaient des effectifs plus importants comme \u00e0 Dissay.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">la transformation du projet d&rsquo;ouverture \u00e0 Brux en \u00a0\u00bb ouverture conditionnelle \u00a0\u00bb comme Chir\u00e9 en Montreuil<\/strong>&#8211; l&rsquo;IA a d\u00e9cid\u00e9 de mettre la situation en attente et de recompter les \u00e9l\u00e8ves en septembre . Il semble que le nombre d&rsquo;\u00e9coles similaires ( 3 classes avec de 80 \u00e0 90 \u00e9l\u00e8ves et des r\u00e9partitions complexes ) ait fait h\u00e9siter l&rsquo;IA \u00e0 effectuer une ouverture en juin.<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_3\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a><strong class=\"spip\">D\u00e9cisions finales<br \/>\n<\/strong><\/h3>\n<p class=\"spip\"><strong class=\"spip\">2 Ouvertures + 3 Annulations de fermetures<\/strong><\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Ligug\u00e9 \u00e9l\u00e9m &#8211; 224 \u00e9l\u00e8ves pour 8 classes soit 28 \u00e9l\u00e8ves de moyenne par classe. Apr\u00e8s ouverture cela ferait 24.89 \u00e9l\u00e8ves par classe.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers Andersen \u00e9l\u00e9m &#8211; 314 \u00e9l\u00e8ves pour 15 classes avec des classes CM1\/CM2 \u00e0 28\/29 par classe avant inclusion ULIS. L&rsquo;\u00e9cole passe \u00e0 16 classes dont 6 \u00ab\u00a0CP \u00e0 12 \u00a0\u00bb + 1 dispositif ULIS.<\/p>\n<p class=\"spip\">+ 3 annulations de fermetures d\u00e9cid\u00e9es au CTSD en mars : St L\u00e9ger de Montbrillais, S\u00e9rigny-Sossais, Chauvigny Guiraudi\u00e8res prim (voir explications au-dessus)<\/p>\n<p class=\"spip\"><strong class=\"spip\">3 Fermetures<\/strong><\/p>\n<p class=\"spip\">Les fermetures ne touchent que des maternelles, la FSU \/ CGT a d\u00e9nonc\u00e9 des effectifs qui restent bien plus \u00e9lev\u00e9s en moyenne en maternelle qu&rsquo;en \u00e9l\u00e9mentaire ( + 2 en moyenne ). L&rsquo;IA a indiqu\u00e9 qu&rsquo;il n&rsquo;acceptait pas les critiques sur le fait qu&rsquo;il p\u00e9naliserait plus la maternelle et que c&rsquo;\u00e9tait la baisse d\u00e9mographique ( &#8211; 400 \u00e9l\u00e8ves annonc\u00e9s) qui justifierait ces fermetures. De plus, il a indiqu\u00e9 qu&rsquo;il y avait beaucoup d&rsquo;absent\u00e9isme en maternelle et donc qu&rsquo;au final, \u00e7a s&rsquo;\u00e9quilibrait. La FSU\/CGT a d\u00e9nonc\u00e9 ces propos<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Dissay mat &#8211; 107 \u00e9l\u00e8ves pour 5 classes, cela fera 26.75 \u00e9l\u00e8ves apr\u00e8s fermeture. La FSU\/CGT a d\u00e9fendu cette situation notamment en terme de mixit\u00e9 sociale bien pr\u00e9sente sur l&rsquo;\u00e9cole.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> La Villedieu du Clain mat &#8211; 51 \u00e9l\u00e8ves pour 3 classes, cela fera 25.50 \u00e9l\u00e8ves apr\u00e8s fermeture<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers Petit Tour mat &#8211; 58 \u00e9l\u00e8ves pour 3 classes annonc\u00e9s, cela fera 29 \u00e9l\u00e8ves par classe apr\u00e8s fermeture &#8211; l&rsquo;IA a indiqu\u00e9 qu&rsquo;il souhaitait une meilleure sectorisation avec la maternelle Poitiers Pasteur<\/p>\n<p class=\"spip\">+ 3 confirmations de fermetures d\u00e9cid\u00e9es en mars :<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Vouill\u00e9 mat &#8211; La FSU\/CGT a fait remonter toutes les situations o\u00f9 le manque de moyens mis sur l&rsquo;\u00e9cole publique va profiter directement \u00e0 l&rsquo;\u00e9cole priv\u00e9e, c&rsquo;est le cas \u00e0 Vouill\u00e9. Dans ce match, la cl\u00e9 de vo\u00fbte est \u00e9videmment la scolarisation des \u00ab Moins de 3 ans \u00bb. La FSU \/ CGT a demand\u00e9 qu&rsquo;un dispositif \u00ab moins de 3 ans \u00bb soit mis en place pour permettre une offre qui puisse contre carrer les campagnes marketing du priv\u00e9. L&rsquo;IA est s\u00e9duit par cette id\u00e9e &#8230; mais plus tard , il \u00e9voque 2019 !?!<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Civray prim &#8211; 100 \u00e9l\u00e8ves pour 6 classes, donc 5 classes de 20 \u00e9l\u00e8ves apr\u00e8s fermeture et avant inclusion ULIS. voir dans la partie d\u00e9cla liminaire FSU\/CGT<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Clou\u00e9 prim &#8211; 57 \u00e9l\u00e8ves pour 3 classes, 28,5 \u00e9l\u00e8ves par classe en quadruple niveaux apr\u00e8s fermeture ! L&rsquo;IA a indiqu\u00e9 que le projet de RPI avec Celles l&rsquo;Evescault avait \u00e9t\u00e9 enfin act\u00e9 par le Sivos de Lusignan ce vendredi et donc que les 7 CM1\/CM2 pourraient aller sur Celles l&rsquo;Evescault. La FSU\/CGT s&rsquo;est alert\u00e9e sur cette mise en place tardive de RPI qui pose des questions sur le transport scolaire, alors que les march\u00e9s ont d\u00e9j\u00e0 \u00e9t\u00e9 attribu\u00e9s entre les transporteurs, et sur la situation du coll\u00e8gue de Clou\u00e9 qui aurait pu b\u00e9n\u00e9ficier d&rsquo;une priorit\u00e9 de recasement sur Celles l&rsquo;Evescault dans le cadre du mouvement.<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_4\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Vote : majoritairement contre<\/h3>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Contre : 8 ( 5 FSU\/CGT, 2 FO, 1 SNALC)<br \/>\nAbstention : 2 ( Unsa)<\/p>\n<p class=\"spip\"><strong class=\"spip\">Suite des op\u00e9rations de carte scolaire<\/strong><\/p>\n<p class=\"spip\">Ces d\u00e9cisions seront pr\u00e9sent\u00e9es au CDEN du 20 juin . Potentiellement, les d\u00e9cisions peuvent \u00eatre encore modifi\u00e9es.<\/p>\n<p class=\"spip\">L&rsquo;IA indique qu&rsquo;il lui reste 2 moyens pour effectuer les ouvertures de rentr\u00e9e 2018 ! Comme demand\u00e9 par la FSU\/CGT, l&rsquo;IA a indiqu\u00e9 qu&rsquo;il n&rsquo;y aurait pas de fermetures \u00e0 la rentr\u00e9e 2018. La FSU\/CGT a indiqu\u00e9 qu&rsquo; 1 moyen dispo avait disparu depuis le CDEN de Mars. L&rsquo;IA a expliqu\u00e9, que comme il avait r\u00e9pondu \u00e0 la demande du SNUipp-FSU de ne pas limiter les temps partiels, il avait d\u00fb prendre 1.4 moyens pour financer cette mesure.<\/p>\n<h3 class=\"spip\" id=\"outil_sommaire_5\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Autres situations port\u00e9es par la FSU\/CGT \u00e0 ce CTSD et\/ou au GT<\/h3>\n<p class=\"spip\"><strong class=\"spip\">Maternelle<\/strong><\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Mignaloux Beauvoir<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> St Benoit Bois d&rsquo;amour maternelle <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Loudun les Lutins maternelle <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers Andersen maternelle <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers Montmidi maternelle<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Naintr\u00e9 Anne Franck<\/p>\n<p class=\"spip\"><strong class=\"spip\">El\u00e9mentaire<\/strong><\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Iteuil <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Buxerolles bourg<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Chasseneuil les groseillers \u00e9l\u00e9mentaire <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Ligug\u00e9 <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers Paul Blet <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Vouill\u00e9 <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers P\u00e9rochon <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Ch\u00e2tellerault Ferry <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> St Benoit Ermitage <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Poitiers Brassens<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Lenclo\u00eetre \u00e9l\u00e9m <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Biard \u00e9l\u00e9m<\/p>\n<p class=\"spip\"><strong class=\"spip\">Primaire\/RPI<\/strong><\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Moncontour <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Chabournay <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Verri\u00e8res<\/p>\n<p class=\"spip\"><strong class=\"spip\">Autres<\/strong><\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> PDMQDC Chapelle Viviers <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Dispositif particulier T. Lain\u00e9 mat -> l&rsquo;IA a indiqu\u00e9 qu&rsquo;un moyen serait attribu\u00e9 en septembre sur les \u00ab\u00a0postes gel\u00e9s\u00a0\u00bb suite aux \u00e9valuations positives du dispositif exp\u00e9rimental par le CARDIE et IA.<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> UPE2A <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Maintien de la d\u00e9charge de direction \u00e0 N+1 (suite \u00e0 une fermeture)<\/p>\n<p class=\"spip\"><strong class=\"spip\">Situation de Jaunay Marigny<\/strong><\/p>\n<p class=\"spip\">La FSU\/CGT a fait remonter son incompr\u00e9hension concernant la sectorisation lors de la campagne d&rsquo;inscriptions de la mairie de Jaunay-Marigny. D&rsquo;une ann\u00e9e sur l&rsquo;autre, la mairie d\u00e9cide de modifier son offre scolaire en mettant les inscriptions sur telle ou telle \u00e9cole, avec Chinc\u00e9 et Parigny en variable. Au final, ce sont les enseignant-e-s qui sont mis-e-s en difficult\u00e9 avec des variations d&rsquo;effectifs tr\u00e8s important. L&rsquo;IA a indiqu\u00e9 qu&rsquo;il mettrait un moyen suppl\u00e9mentaire (brigade) toute l&rsquo;ann\u00e9e sur Jaunay Clan pour permettre d&rsquo;y faire face.<\/p>\n<hr class=\"spip\" \/>\n<h3 class=\"spip\" id=\"outil_sommaire_6\"><a title=\"Sommaire\" href=\"http:\/\/86.snuipp.fr\/spip.php?page=backend&#038;id_rubrique=#outil_sommaire\" class=\"sommaire_ancre\"> <\/a>Questions diverses de la FSU \/ CGT : 1er degr\u00e9 en coll\u00e8ge, ULIS, EREA, contactuel-le-s, &#8211; de 3 ans<\/h3>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Pr\u00e9sence d&rsquo;\u00e9l\u00e8ves du primaire au coll\u00e8ge ?<\/strong><\/p>\n<p class=\"spip\">L&rsquo;IA a indiqu\u00e9 que seule une \u00e9cole, celle de l&rsquo;Isle Jourdain, \u00e9tait concern\u00e9e \u00e0 la rentr\u00e9e 2018 par des classes transf\u00e9r\u00e9es au coll\u00e8ge. Pour rappel, suite aux travaux dans l&rsquo;\u00e9cole \u00e9l\u00e9mentaire l&rsquo;ann\u00e9e prochaine, les classes de CE et CM seront dans le coll\u00e8ge de l&rsquo; Isle Jourdain, \u00e0 la rentr\u00e9e 2018. Il y a d&rsquo;ailleurs eu un message pour pr\u00e9venir la profession \u00e0 ce sujet dans le cadre du mouvement. Le SNUipp-FSU a rappel\u00e9 que l&rsquo;exp\u00e9rimentation \u00e9cole \/ coll\u00e8ge existait d\u00e9j\u00e0 sur ce site depuis 4 ans avec de multiples \u00e9volutions, et cela, sans qu&rsquo;aucun bilan public ne soit effectu\u00e9. Le SNUipp-FSU a demand\u00e9 qu&rsquo;un bilan en CDEN soit effectu\u00e9. L&rsquo;IA a donn\u00e9 son accord de principe.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Comptabilisation des ULIS au sein des \u00e9coles<\/strong><\/p>\n<p class=\"spip\">Le SNUipp-FSU a rappel\u00e9 \u00e0 l&rsquo;IA l&rsquo;importance de comptabiliser les \u00e9l\u00e8ves d&rsquo;ULIS dans les effectifs tout en conservant l&rsquo;affectation en dispositif.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Mission des PE \u00e9duc de l&rsquo;EREA \u00e0 la rentr\u00e9e 2018<\/strong><\/p>\n<p class=\"spip\">L&rsquo;IA a confirm\u00e9 les propos du rectorat sur la r\u00e9forme des EREA ( plus ou moins, l&rsquo;uniformisation des missions entre enseignant-e et enseignant-e \u00e9ducateur\/trice). Cela se mettrait en place \u00e0 la rentr\u00e9e 2019. La FSU \/ CGT avait \u00e9t\u00e9 alert\u00e9e sur un message de la directrice indiquant \u00a0\u00bb vouloir anticiper la r\u00e9forme \u00a0\u00bb . L&rsquo;IA a pr\u00e9cis\u00e9 que cette \u00ab\u00a0anticipation\u00a0\u00bb \u00e9tait la r\u00e9flexion et la construction de propositions pour la rentr\u00e9e 2019. Rien ne pouvait \u00eatre demand\u00e9 aux personnels actuellement en place, sauf pour ceux\/celles qui en feraient la demande en tant que volontaires. La FSU\/CGT d\u00e9fend un internat \u00e9ducatif de qualit\u00e9, loin du projet actuel de l&rsquo;administration.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Contractuel-les 1er degr\u00e9<\/strong><\/p>\n<p class=\"spip\">L&rsquo;IA a indiqu\u00e9 que le d\u00e9partement \u00e9tait en l\u00e9ger surnombre et donc, que la question de recrutement de contractuel-le-s n&rsquo;\u00e9tait pas \u00e0 l&rsquo;ordre du jour. Cette position pouvait \u00e9voluer en fonction du d\u00e9roulement de l&rsquo;ann\u00e9e. La FSU \/ CGT a exprim\u00e9 la demande que le nombre de stagiaires recrut\u00e9s soit maximum, notamment en faisant appel \u00e0 la liste compl\u00e9mentaire, pour ne pas \u00eatre en manque de personnels en cours d&rsquo;ann\u00e9e. La FSU\/CGT a demand\u00e9 que la position de l&rsquo;IA concernant les contractuel-le-s soit prise avant les vacances d&rsquo;automne, car apr\u00e8s, les conditions d&#8217;emploi de ces coll\u00e8gues s&rsquo;en voient d\u00e9grad\u00e9es puisque ils\/elles ne sont plus pay\u00e9-e-s en juillet et ao\u00fbt.<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> <strong class=\"spip\">Consignes IEN sur la scolarisation des \u00a0\u00bb moins de 3 ans \u00a0\u00bb hors dispositif<\/strong><\/p>\n<p class=\"spip\">La FSU \/ CGT a fait remonter l&rsquo;inqui\u00e9tude de plusieurs \u00e9quipes auxquelles les IEN demandent d&rsquo;accueillir des TPS, alors qu&rsquo;elles estiment que les conditions ne sont pas r\u00e9ussies pour accueillir qualitativement ces \u00e9l\u00e8ves. L&rsquo;IA a indiqu\u00e9 que ce ne sont pas les directeurs \/trices qui d\u00e9cident, mais un \u00e9change \u00e0 3 : \u00e9quipes, IEN et mairie. La FSU \/ CGT a indiqu\u00e9 qu&rsquo;effectivement c&rsquo;\u00e9tait dans l&rsquo;\u00e9change que la condition d&rsquo;accueil devait \u00eatre d\u00e9finie et que les \u00e9quipes, qui sont tous les jours sur le terrain, doivent \u00eatre \u00e9cout\u00e9es et entendues prioritairement.<\/p>\n<p class=\"spip\"><i class=\"spip\">pour la FSU\/CGT, Fr\u00e9d\u00e9ric Belly, Julien Caillaud, Fr\u00e9d\u00e9rique Delage, Anne-Sophie Decha, Charles Girault, Matthieu Menaut, Julie Saulnier<\/i><\/p>\n<dl class='spip_document_3492 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/jpg\/logo-fsu-cgt.jpg' width='520' height='346' alt='JPEG - 122.1 ko' style='height:346px;width:520px;' class='' \/><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>logo-fsu-cgt<\/strong><\/dt>\n<\/dl>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CTSD du 11 juin <br \/>Retrouvez ci-dessous le compte rendu complet du CTSD o\u00f9 l&rsquo;IA a prononc\u00e9 les d\u00e9cisions d&rsquo;ouvertures et fermetures de ce lien :http:\/\/86.snuipp.fr\/spip.php ?article3974 <br \/>1- D\u00e9claration liminaire : \ufeffprotocole ruralit\u00e9, UPE2A, IEN\ufeff <br \/>2- D\u00e9cisions d&rsquo;ouvertures et fermetures : explications, vote, la suite <br \/>3- Questions diverses : 1er degr\u00e9 en coll\u00e8ge, ULIS, EREA, contactuel-le-s, moins de 3 ans <br \/>Pr\u00e9sent-e-s : M. Claverie ( IA ) , M. Monlun ( SG) , M. (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique36\" rel=\"directory\">CTSD<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-142","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A ... - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A ... - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"CTSD du 11 juin Retrouvez ci-dessous le compte rendu complet du CTSD o\u00f9 l&#039;IA a prononc\u00e9 les d\u00e9cisions d&#039;ouvertures et fermetures de ce lien :http:\/\/86.snuipp.fr\/spip.php ?article3974 1- D\u00e9claration liminaire : \ufeffprotocole ruralit\u00e9, UPE2A, IEN\ufeff 2- D\u00e9cisions d&#039;ouvertures et fermetures : explications, vote, la suite 3- Questions diverses : 1er degr\u00e9 en coll\u00e8ge, ULIS, EREA, contactuel-le-s, moins de 3 ans Pr\u00e9sent-e-s : M. Claverie ( IA ) , M. Monlun ( SG) , M. (...) - CTSD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-14T15:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/\",\"name\":\"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A ... - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png\",\"datePublished\":\"2018-06-14T15:08:48+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A ... - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/","og_locale":"fr_FR","og_type":"article","og_title":"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A ... - FSU-SNUipp 86","og_description":"CTSD du 11 juin Retrouvez ci-dessous le compte rendu complet du CTSD o\u00f9 l'IA a prononc\u00e9 les d\u00e9cisions d'ouvertures et fermetures de ce lien :http:\/\/86.snuipp.fr\/spip.php ?article3974 1- D\u00e9claration liminaire : \ufeffprotocole ruralit\u00e9, UPE2A, IEN\ufeff 2- D\u00e9cisions d'ouvertures et fermetures : explications, vote, la suite 3- Questions diverses : 1er degr\u00e9 en coll\u00e8ge, ULIS, EREA, contactuel-le-s, moins de 3 ans Pr\u00e9sent-e-s : M. Claverie ( IA ) , M. Monlun ( SG) , M. (...) - CTSD","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-06-14T15:08:48+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/","name":"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A ... - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png","datePublished":"2018-06-14T15:08:48+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3978.png"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/06\/14\/ctsd-du-11-juin-2018-ouvertures-fermetures-convention-rurale-upe2a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"CTSD du 11 juin 2018 : ouvertures\/fermetures, convention rurale, UPE2A &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/142\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}