{"id":168,"date":"2018-04-10T14:36:23","date_gmt":"2018-04-10T14:36:23","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/"},"modified":"2018-04-10T14:36:23","modified_gmt":"2018-04-10T14:36:23","slug":"hors-classe-2018-rsultats-le-22-mai-pour-la-vienne","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/","title":{"rendered":"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne !"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg\" alt=\"\" align=\"right\" width=\"816\" height=\"544\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">La circulaire d\u00e9partementale est sortie<\/p>\n<p class=\"spip\"><a href=\"https:\/\/www.intra.ac-poitiers.fr\/mes-rubriques\/note-de-service-promotions-a-la-hors-classe-2018-250666.kjsp?RH=1192696847494\" class=\"spip_out\">retrouvez la sur ce lien.<\/a><\/p>\n<p class=\"spip\">Elle concerne tou-te-s les coll\u00e8gues qui sont :<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> \u00e0 l&rsquo;\u00e9chelon 11, <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> \u00e0 l&rsquo;\u00e9chelon 10 <br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> ou au moins depuis 2 ans dans l&rsquo;\u00e9chelon 9 au 31\/8\/2018.<\/p>\n<p class=\"spip\">Normalement, tous et toutes les PE \u00ab\u00a0promouvables\u00a0\u00bb ont \u00e9t\u00e9 inform\u00e9-e-s individuellement via l&rsquo;application I-PROF. Si ce n&rsquo;est pas votre cas, alertez rapidement la DPE5 et le SNUipp-FSU 86.<\/p>\n<dl class='spip_document_3312 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L520xH321\/calculateur-slideshow-slideshow_slideshow-dd097.jpg' width='520' height='321' alt='JPEG - 49.7 ko' style='height:321px;width:520px;' class='' \/><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>calculateur-slideshow-slideshow_slideshow<\/strong><\/dt>\n<\/dl>\n<p class=\"spip\">Tous les coll\u00e8gues \u00e9ligibles seront class\u00e9-e-s selon un bar\u00e8me qui comprend :<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> des points pour l&rsquo;\u00e9chelon<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> des points pour l&rsquo;avis de l&rsquo;IA<\/p>\n<p class=\"spip\"><a href=\"http:\/\/86.snuipp.fr\/spip.php?article3748&#038;var_recherche=hors%20classe\" class=\"spip_out\">lien vers les points du bar\u00e8me<\/a><\/p>\n<p class=\"spip\">Pour rappel, cette ann\u00e9e est transitoire, tous les coll\u00e8gues \u00e9ligibles auront un avis formul\u00e9 par leur IEN en fonction de leur ancienne note et de leur dossier iprof ( qui peut \u00eatre enrichi du 11 au 27 avril).<\/p>\n<p class=\"spip\">L&rsquo;IA doit s&rsquo;appuyer ensuite sur cet avis pour \u00e9mettre le sien : excellent, tr\u00e8s satisfaisant, satisfaisant, \u00e0 consolider. Attention ! cet avis sera aussi celui des campagnes suivantes si vous n&rsquo;\u00eates pas promu-e-s cette session ! L&rsquo;avis de l&rsquo;IA sera consultable \u00e0 partir du 14 mai.<\/p>\n<p class=\"spip\">La CAPD est pr\u00e9vue le 22 mai.<\/p>\n<h3 class=\"spip\">Acc\u00e8s \u00e0 la hors classe pour toutes et tous ?<\/h3>\n<p class=\"spip\">Dans le cadre de PPCR, les agents ayant une carri\u00e8re compl\u00e8te doivent voir leur carri\u00e8re se d\u00e9rouler sur au moins deux grades. Afin que cela soit r\u00e9alisable, le SNUipp et la FSU avaient port\u00e9 l&rsquo;acc\u00e8s automatique \u00e0 la hors classe notamment pour les retraitables.<\/p>\n<p class=\"spip\">Aujourd&rsquo;hui le bar\u00e8me actuel ne permet pas de garantir l&rsquo;avancement \u00e0 la hors classe aux coll\u00e8gues qui partiront \u00e0 la retraite en 2019 ou 2020. Pour certain-es d&rsquo;entre eux\/elles, cela s&rsquo;ajoute au report de leur prochaine promotion apr\u00e8s leur reclassement dans la nouvelle grille indiciaire.<\/p>\n<p class=\"spip\">Le SNUipp-FSU est d\u00e9j\u00e0 intervenu aupr\u00e8s du minist\u00e8re sur la n\u00e9cessit\u00e9 de porter une attention particuli\u00e8re \u00e0 ces personnels.<\/p>\n<p class=\"spip\"><strong class=\"spip\">Le SNUipp-FSU vous propose un courrier type<\/strong> (mod\u00e8le joint) \u00e0 envoyer par chaque coll\u00e8gue concern\u00e9-e sous couvert de l&rsquo;IEN au DASEN et copie \u00e0 la section d\u00e9partementale SNUipp-FSU. Cela permettra d&rsquo;intervenir en CAPD.<\/p>\n<dl class='spip_document_3320 spip_documents spip_documents_center' >\n<dt><a href=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/zip\/12_04_2018__courrier_petition-20180412102243.docx.zip\" title='Zip - 10.1 ko' type=\"application\/zip\"><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L52xH52\/zip-581d9.png' width='52' height='52' alt='Zip - 10.1 ko' style='height:52px;width:52px;' class=' format_png' \/><\/a><\/dt>\n<dt class='spip_doc_titre' style='width:120px;'><strong>courrier_HC<\/strong><\/dt>\n<\/dl>\n<dl class='spip_document_3310 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L234xH216\/elus-person_slideshow-8-73b6d.jpg' width='234' height='216' alt='JPEG - 13.4 ko' style='height:216px;width:234px;' class='' \/><\/dt>\n<dt class='spip_doc_titre' style='width:234px;'><strong>elus-person_slideshow<\/strong><\/dt>\n<\/dl>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La circulaire d\u00e9partementale est sortie <br \/>retrouvez la sur ce lien. <br \/>Elle concerne tou-te-s les coll\u00e8gues qui sont : <br \/>\u00e0 l&rsquo;\u00e9chelon 11, <br \/>\u00e0 l&rsquo;\u00e9chelon 10 <br \/>ou au moins depuis 2 ans dans l&rsquo;\u00e9chelon 9 au 31\/8\/2018. <br \/>Normalement, tous et toutes les PE \u00ab\u00a0promouvables\u00a0\u00bb ont \u00e9t\u00e9 inform\u00e9-e-s individuellement via l&rsquo;application I-PROF. Si ce n&rsquo;est pas votre cas, alertez rapidement la DPE5 et le SNUipp-FSU 86. <br \/>Tous les coll\u00e8gues \u00e9ligibles seront class\u00e9-e-s selon un bar\u00e8me qui comprend : <br \/>des points pour (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique120\" rel=\"directory\">Promotions<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-168","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne ! - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne ! - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"La circulaire d\u00e9partementale est sortie retrouvez la sur ce lien. Elle concerne tou-te-s les coll\u00e8gues qui sont : \u00e0 l&#039;\u00e9chelon 11, \u00e0 l&#039;\u00e9chelon 10 ou au moins depuis 2 ans dans l&#039;\u00e9chelon 9 au 31\/8\/2018. Normalement, tous et toutes les PE &quot;promouvables&quot; ont \u00e9t\u00e9 inform\u00e9-e-s individuellement via l&#039;application I-PROF. Si ce n&#039;est pas votre cas, alertez rapidement la DPE5 et le SNUipp-FSU 86. Tous les coll\u00e8gues \u00e9ligibles seront class\u00e9-e-s selon un bar\u00e8me qui comprend : des points pour (...) - Promotions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-10T14:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/\",\"name\":\"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne ! - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg\",\"datePublished\":\"2018-04-10T14:36:23+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne ! - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/","og_locale":"fr_FR","og_type":"article","og_title":"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne ! - FSU-SNUipp 86","og_description":"La circulaire d\u00e9partementale est sortie retrouvez la sur ce lien. Elle concerne tou-te-s les coll\u00e8gues qui sont : \u00e0 l'\u00e9chelon 11, \u00e0 l'\u00e9chelon 10 ou au moins depuis 2 ans dans l'\u00e9chelon 9 au 31\/8\/2018. Normalement, tous et toutes les PE \"promouvables\" ont \u00e9t\u00e9 inform\u00e9-e-s individuellement via l'application I-PROF. Si ce n'est pas votre cas, alertez rapidement la DPE5 et le SNUipp-FSU 86. Tous les coll\u00e8gues \u00e9ligibles seront class\u00e9-e-s selon un bar\u00e8me qui comprend : des points pour (...) - Promotions","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-04-10T14:36:23+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/","name":"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne ! - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg","datePublished":"2018-04-10T14:36:23+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3880.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/04\/10\/hors-classe-2018-rsultats-le-22-mai-pour-la-vienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Hors classe 2018 : r\u00e9sultats le 22 mai pour la Vienne !"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=168"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/168\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}