{"id":20422,"date":"2021-03-25T14:37:05","date_gmt":"2021-03-25T13:37:05","guid":{"rendered":"http:\/\/snuipp86.fr\/?p=20422"},"modified":"2021-03-25T14:37:05","modified_gmt":"2021-03-25T13:37:05","slug":"capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/","title":{"rendered":"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-medium wp-image-18837 aligncenter\" src=\"https:\/\/snuipp86.fr\/wp-content\/uploads\/2020\/05\/logo-ct-300x127.jpg\" alt=\"\" width=\"300\" height=\"127\" \/><\/p>\n<p><u>Textes de r\u00e9f\u00e9rence<\/u>:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000043149138\">D\u00e9cret n\u00b0 2021-176 du 17 f\u00e9vrier 2021 portant modification temporaire des modalit\u00e9s de calcul du capital d\u00e9c\u00e8s servi aux ayants droit de l&rsquo;agent public d\u00e9c\u00e9d\u00e9<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Les ayant-droit du fonctionnaire ou d\u2019un.e agent.e contractuel.le d\u00e9c\u00e9d\u00e9.e en activit\u00e9 per\u00e7oivent, sous conditions, une prestation appel\u00e9e capital d\u00e9c\u00e8s.<br \/>\nPour m\u00e9moire, la prestation consistait, auparavant, \u00e0 un montant forfaitaire et variait en fonction de la position du d\u00e9funt : en activit\u00e9 ou retrait\u00e9 et ne concernait que les titulaires.<\/p>\n<p>Dor\u00e9navant, le montant du capital sera d\u00e9termin\u00e9 par la r\u00e9mun\u00e9ration perc\u0327ue par l\u2019agent.e avant son d\u00e9c\u00e8s.<\/p>\n<p>Ces nouvelles dispositions sont entr\u00e9es en vigueur au 1<sup>er<\/sup> \u00a0janvier 2021 mais sont temporaires et seront abrog\u00e9es au 1<sup>er<\/sup> \u00a0janvier 2022. Elles s\u2019appliqueront donc aux d\u00e9c\u00e8s survenant durant l\u2019ann\u00e9e 2021. Ce d\u00e9cret temporaire devrait \u00eatre formalis\u00e9 dans une loi dans laquelle les dispositions qu\u2019il porte devraient \u00eatre p\u00e9rennis\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<h1><strong><u>Qu\u2019est-ce-que le capital d\u00e9c\u00e8s ? <\/u><\/strong><\/h1>\n<p>C\u2019est une prestation vers\u00e9e par l\u2019employeur aux ayants droits d\u2019un.e fonctionnaire qui d\u00e9c\u00e8de alors qu\u2019il.elle est en activit\u00e9, en d\u00e9tachement, en disponibilit\u00e9 pour raison de sant\u00e9, ou sous les drapeaux.<\/p>\n<h1><\/h1>\n<h1><strong><u>Qui le touche ? <\/u><\/strong><\/h1>\n<p>Sont concern\u00e9s les ayants droit des fonctionnaires des trois versants de la FP, les agents publics relevant du r\u00e9gime de l\u2019Ircantec, des militaires et des magistrats de l\u2019ordre judiciaire.<\/p>\n<h1><strong><u>Divers cas de figure : <\/u><\/strong><\/h1>\n<table width=\"718\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"419\">D\u00e9funt ayant des enfants<\/td>\n<td colspan=\"2\" width=\"299\">D\u00e9funt sans enfant<\/td>\n<\/tr>\n<tr>\n<td width=\"282\">D\u00e9funt mari\u00e9 ou pacs\u00e9<\/td>\n<td width=\"137\">Autre cas<\/td>\n<td width=\"155\">D\u00e9funt mari\u00e9 ou pacs\u00e9<\/td>\n<td width=\"144\">Autre cas<\/td>\n<\/tr>\n<tr>\n<td width=\"282\">Le capital d\u00e9c\u00e8s est partag\u00e9 :<br \/>\n&#8211; 1\/3 \u00e0 l&rsquo;\u00e9poux\/l\u2019\u00e9pouse non s\u00e9par\u00e9.e ou partenaire de Pacs depuis 2 ans.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2\/3 aux enfants du fonctionnaire,<\/td>\n<td width=\"137\">Les enfants re\u00e7oivent l&rsquo;int\u00e9gralit\u00e9 du capital d\u00e9c\u00e8s.<\/td>\n<td rowspan=\"2\" width=\"155\">L&rsquo;\u00e9poux ou le partenaire de Pacs re\u00e7oit l&rsquo;int\u00e9gralit\u00e9 du capital d\u00e9c\u00e8s.<\/td>\n<td rowspan=\"2\" width=\"144\">Le capital est vers\u00e9 aux ascendants \u00e0 la charge du fonctionnaire au moment de son d\u00e9c\u00e8s.<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"419\">Les enfants ayant-droit doivent \u00eatre \u00e2g\u00e9s de moins de 21 ans ou \u00eatre reconnus infirme au jour du d\u00e9c\u00e8s.<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"718\">Dans tous ces cas, les ascendants ou descendants doivent ne pas \u00eatre imposables \u00e0 l&rsquo;imp\u00f4t sur le revenu.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h1><strong><u>Combien ?<\/u><\/strong><\/h1>\n<p><strong>\u00a0<\/strong><\/p>\n<table width=\"718\">\n<tbody>\n<tr>\n<td width=\"359\"><strong>D\u00e9c\u00e8s en 2021 :<\/strong><\/td>\n<td width=\"359\"><strong>D\u00e9c\u00e8s avant 2021 :<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"359\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Si la personne d\u00e9c\u00e9d\u00e9e est un fonctionnaire titulaire, le montant du capital d\u00e9c\u00e8s correspond \u00e0 sa derni\u00e8re r\u00e9mun\u00e9ration brute annuelle de l\u2019ann\u00e9e pr\u00e9c\u00e9dant le d\u00e9c\u00e8s, indemnit\u00e9s accessoires comprises.<\/p>\n<p><em>Les indemnit\u00e9s accessoires sont:<\/em><\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0 <em>Enseignement et jury (cf. D\u00e9cret n\u00b0 2010-235 du 5 mars 2010) <\/em><\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0 <em>Affectation (cf. D\u00e9cret n\u00b0 89-259 du 24 avril 1989)<\/em><\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0 <em>Primes et indemnit\u00e9s li\u00e9es \u00e0 la mobilit\u00e9<\/em><\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0 <em>Un forfait \u00ab\u00a0mobilit\u00e9s durables\u00a0\u00bb de 200 euros par an pour les trajets domicile-travail des agents<\/em><\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0 <em>Une prime exceptionnelle vers\u00e9e aux agents mobilis\u00e9s dans le cadre de l&rsquo;\u00e9tat d&rsquo;urgence sanitaire<\/em><\/p>\n<p>&#8211; Si la personne d\u00e9c\u00e9d\u00e9e est un agent non titulaire, le montant du capital d\u00e9c\u00e8s correspond au gain per\u00e7u sur les 12 derniers mois pr\u00e9c\u00e9dant la date du d\u00e9c\u00e8s.<\/p>\n<p>&nbsp;<\/td>\n<td width=\"359\"><u>D\u00e9c\u00e8s apr\u00e8s l\u2019\u00e2ge minimum de retraite : <\/u>Le capital d\u00e9c\u00e8s est \u00e9gal \u00e0 3 472 \u20ac. Aucune majoration n&rsquo;est pr\u00e9vue pour les enfants.<u><br \/>\nD\u00e9c\u00e8s avant l\u2019\u00e2ge minimum de retraite : <\/u><\/p>\n<p>Cas g\u00e9n\u00e9ral 13 888 \u20ac.<br \/>\nCas particuliers<\/p>\n<ol>\n<li><em>D\u00e9c\u00e8s suite \u00e0 accident de service ou de maladie professionnelle, <\/em><\/li>\n<\/ol>\n<p><em>le capital d\u00e9c\u00e8s est \u00e9gal \u00e0 12 fois le montant du dernier traitement indiciaire brut mensuel du d\u00e9funt.<\/em><\/p>\n<ol>\n<li><em>D\u00e9c\u00e8s suite \u00e0 attentat ou d\u2019une lutte dans l&rsquo;exercice de ses fonctions ou d&rsquo;un acte de d\u00e9vouement dans un int\u00e9r\u00eat public ou pour sauver la vie d&rsquo;une ou plusieurs personnes.<\/em><\/li>\n<\/ol>\n<p><em>Le capital d\u00e9c\u00e8s tel que calcul\u00e9 pour un d\u00e9c\u00e8s \u201csuite \u00e0 accident de service ou de maladie professionnelle\u201d est vers\u00e9 3 ann\u00e9es de suite, \u00e0 hauteur de ce m\u00eame montant:<\/em><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <em>\u00a01<sup>er<\/sup> \u00a0versement a lieu au d\u00e9c\u00e8s du fonctionnaire, <\/em><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <em>les 2 autres, au jour anniversaire de l&rsquo;\u00e9v\u00e9nement \u00e0 l&rsquo;origine du d\u00e9c\u00e8s.<\/em><\/p>\n<p>Qu\u2019il s\u2019agisse du cas g\u00e9n\u00e9ral ou des cas particuliers, chaque enfant b\u00e9n\u00e9ficiaire du capital d\u00e9c\u00e8s re\u00e7oit une somme compl\u00e9mentaire de 833,36 \u20ac.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li>\n<h1><strong><u>Comment et dans quel d\u00e9lai ?<\/u><\/strong><\/h1>\n<\/li>\n<\/ul>\n<p>Les ayants droit doivent faire la demande dans les deux ans suivant le d\u00e9c\u00e8s aupr\u00e8s de l&rsquo;administration employeur du fonctionnaire d\u00e9c\u00e9d\u00e9.<br \/>\nIl est n\u00e9cessaire que les\u00a0 ayants-droit se rapprochent de l\u2019administration du fonctionnaire d\u00e9c\u00e9d\u00e9 afin de conna\u00eetre la liste des pi\u00e8ces \u00e0 fournir.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Textes de r\u00e9f\u00e9rence: &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 D\u00e9cret n\u00b0 2021-176 du 17 f\u00e9vrier 2021 portant modification temporaire des modalit\u00e9s de calcul du capital d\u00e9c\u00e8s servi aux ayants droit de l&rsquo;agent public d\u00e9c\u00e9d\u00e9 &nbsp; Les ayant-droit du fonctionnaire ou d\u2019un.e agent.e contractuel.le d\u00e9c\u00e9d\u00e9.e en activit\u00e9 per\u00e7oivent, sous conditions, une prestation appel\u00e9e capital d\u00e9c\u00e8s. Pour m\u00e9moire, la prestation consistait, auparavant, \u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[22],"class_list":["post-20422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","tag-droits-des-personnels"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021 - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021 - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Textes de r\u00e9f\u00e9rence: &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 D\u00e9cret n\u00b0 2021-176 du 17 f\u00e9vrier 2021 portant modification temporaire des modalit\u00e9s de calcul du capital d\u00e9c\u00e8s servi aux ayants droit de l&rsquo;agent public d\u00e9c\u00e9d\u00e9 &nbsp; Les ayant-droit du fonctionnaire ou d\u2019un.e agent.e contractuel.le d\u00e9c\u00e9d\u00e9.e en activit\u00e9 per\u00e7oivent, sous conditions, une prestation appel\u00e9e capital d\u00e9c\u00e8s. Pour m\u00e9moire, la prestation consistait, auparavant, \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-25T13:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"232\" \/>\n\t<meta property=\"og:image:height\" content=\"218\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matthieu Menaut\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matthieu Menaut\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/\",\"name\":\"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021 - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg\",\"datePublished\":\"2021-03-25T13:37:05+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/5a96b33672b90a1385fd0b096fd5ebcb\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#primaryimage\",\"url\":\"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg\",\"contentUrl\":\"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg\",\"width\":232,\"height\":218},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/5a96b33672b90a1385fd0b096fd5ebcb\",\"name\":\"Matthieu Menaut\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/03e70f897b03256ddca91d16c3e33a876c31abbf1b31cb48e60e770f684a04d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/03e70f897b03256ddca91d16c3e33a876c31abbf1b31cb48e60e770f684a04d1?s=96&d=mm&r=g\",\"caption\":\"Matthieu Menaut\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/mmenaut\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021 - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021 - FSU-SNUipp 86","og_description":"Textes de r\u00e9f\u00e9rence: &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 D\u00e9cret n\u00b0 2021-176 du 17 f\u00e9vrier 2021 portant modification temporaire des modalit\u00e9s de calcul du capital d\u00e9c\u00e8s servi aux ayants droit de l&rsquo;agent public d\u00e9c\u00e9d\u00e9 &nbsp; Les ayant-droit du fonctionnaire ou d\u2019un.e agent.e contractuel.le d\u00e9c\u00e9d\u00e9.e en activit\u00e9 per\u00e7oivent, sous conditions, une prestation appel\u00e9e capital d\u00e9c\u00e8s. Pour m\u00e9moire, la prestation consistait, auparavant, \u00e0 [&hellip;]","og_url":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2021-03-25T13:37:05+00:00","og_image":[{"width":232,"height":218,"url":"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg","type":"image\/jpeg"}],"author":"Matthieu Menaut","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matthieu Menaut","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/","url":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/","name":"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021 - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg","datePublished":"2021-03-25T13:37:05+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/5a96b33672b90a1385fd0b096fd5ebcb"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#primaryimage","url":"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg","contentUrl":"https:\/\/snuipp86.fr\/wp-content\/uploads\/2019\/12\/loupe-4-f55ff.jpg","width":232,"height":218},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2021\/03\/25\/capital-deces-pour-les-ayant-droit-des-fonctionnaires-et-contractuels-du-changement-pour-lannee-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Capital d\u00e9c\u00e8s pour les ayant droit des fonctionnaires et contractuels : du changement pour l\u2019ann\u00e9e 2021"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/5a96b33672b90a1385fd0b096fd5ebcb","name":"Matthieu Menaut","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/03e70f897b03256ddca91d16c3e33a876c31abbf1b31cb48e60e770f684a04d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/03e70f897b03256ddca91d16c3e33a876c31abbf1b31cb48e60e770f684a04d1?s=96&d=mm&r=g","caption":"Matthieu Menaut"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/mmenaut\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/20422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=20422"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/20422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media\/18106"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=20422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=20422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=20422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}