{"id":221,"date":"2018-01-17T11:41:42","date_gmt":"2018-01-17T11:41:42","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/"},"modified":"2018-01-17T11:41:42","modified_gmt":"2018-01-17T11:41:42","slug":"les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/","title":{"rendered":"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg\" alt=\"\" align=\"right\" width=\"427\" height=\"240\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">Communiqu\u00e9 FSU du mardi 16 janvier 2018<\/p>\n<p class=\"spip\">Le gouvernement pr\u00e9pare un projet de loi \u00ab asile-immigration \u00bb. La FSU est vigilante sur les dispositions que contiendra ce texte de loi et interviendra notamment pour qu&rsquo;il ne contienne aucune mesure discriminatoire. Comme nombre d&rsquo;associations et d&rsquo;organisations, la FSU est porteuse de propositions pour assurer avec respect et dignit\u00e9 l&rsquo;accueil des migrants et pour, avec eux, leur permettre de se construire un avenir dans notre pays. Si a priori le texte contient quelques mesures en faveur de la protection des personnes, l&rsquo;esprit g\u00e9n\u00e9ral est celui d&rsquo;une conception suspicieuse de l&rsquo;accueil.<\/p>\n<p class=\"spip\">La FSU interpelle le gouvernement sur les dispositions contenues dans la circulaire du minist\u00e8re de l&rsquo;Int\u00e9rieur \u00ab relative au relogement des personnes b\u00e9n\u00e9ficiaires d&rsquo;une protection internationale \u00bb publi\u00e9e le 12 d\u00e9cembre dernier. En effet, ce texte pr\u00e9voit un recensement des migrant.e.s dans les centres d&rsquo;h\u00e9bergement d&rsquo;urgence, ce qui remet en question la protection et l&rsquo;accueil inconditionnels de toute personne en besoin d&rsquo;aide et d&rsquo;accompagnement.<\/p>\n<p class=\"spip\">Pour la FSU, les centres d&rsquo;h\u00e9bergement d&rsquo;urgence et de soins doivent rester des lieux de protection o\u00f9 toute personne ne peut \u00eatre ni menac\u00e9e, ni contr\u00f4l\u00e9e.<\/p>\n<p class=\"spip\">De plus, par la mise en \u0153uvre de contr\u00f4les pr\u00e9fectoraux au sein des centres d&rsquo;h\u00e9bergement avec l&rsquo;objectif de proc\u00e9der \u00e0 des tris administratifs en vue d&rsquo;expulsions, cette circulaire contrevient \u00e0 l&rsquo;article L345.2.2 du Code de l&rsquo;action sociale et des familles qui stipule notamment que \u00ab Toute personne sans abri en situation de d\u00e9tresse m\u00e9dicale, psychique ou sociale a acc\u00e8s, \u00e0 tout moment, \u00e0 un dispositif d&rsquo;h\u00e9bergement d&rsquo;urgence \u00bb permettant \u00ab ..dans des conditions d&rsquo;accueil conformes \u00e0 la dignit\u00e9 de la personne humaine, de b\u00e9n\u00e9ficier de prestations\u2026. \u00bb et \u00ab &#8230;de lui apporter l&rsquo;aide justifi\u00e9e par son \u00e9tat \u00bb.<\/p>\n<p class=\"spip\">C&rsquo;est pourquoi la FSU juge cette circulaire inacceptable. Elle soutient les associations humanitaires et les organisations, qui, comme elle, en demandent le retrait.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Communiqu\u00e9 FSU du mardi 16 janvier 2018 <br \/>Le gouvernement pr\u00e9pare un projet de loi \u00ab asile-immigration \u00bb. La FSU est vigilante sur les dispositions que contiendra ce texte de loi et interviendra notamment pour qu&rsquo;il ne contienne aucune mesure discriminatoire. Comme nombre d&rsquo;associations et d&rsquo;organisations, la FSU est porteuse de propositions pour assurer avec respect et dignit\u00e9 l&rsquo;accueil des migrants et pour, avec eux, leur permettre de se construire un avenir dans (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique249\" rel=\"directory\">L&rsquo;ACTUALIT\u00c9<\/a><br \/>\n\/<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?mot310\" rel=\"tag\">Les r\u00e9formes<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-221","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Communiqu\u00e9 FSU du mardi 16 janvier 2018 Le gouvernement pr\u00e9pare un projet de loi \u00ab asile-immigration \u00bb. La FSU est vigilante sur les dispositions que contiendra ce texte de loi et interviendra notamment pour qu&#039;il ne contienne aucune mesure discriminatoire. Comme nombre d&#039;associations et d&#039;organisations, la FSU est porteuse de propositions pour assurer avec respect et dignit\u00e9 l&#039;accueil des migrants et pour, avec eux, leur permettre de se construire un avenir dans (...) - L&#039;ACTUALIT\u00c9 \/ Les r\u00e9formes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-17T11:41:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/\",\"name\":\"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg\",\"datePublished\":\"2018-01-17T11:41:42+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/","og_locale":"fr_FR","og_type":"article","og_title":"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s - FSU-SNUipp 86","og_description":"Communiqu\u00e9 FSU du mardi 16 janvier 2018 Le gouvernement pr\u00e9pare un projet de loi \u00ab asile-immigration \u00bb. La FSU est vigilante sur les dispositions que contiendra ce texte de loi et interviendra notamment pour qu'il ne contienne aucune mesure discriminatoire. Comme nombre d'associations et d'organisations, la FSU est porteuse de propositions pour assurer avec respect et dignit\u00e9 l'accueil des migrants et pour, avec eux, leur permettre de se construire un avenir dans (...) - L'ACTUALIT\u00c9 \/ Les r\u00e9formes","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-01-17T11:41:42+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/","name":"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg","datePublished":"2018-01-17T11:41:42+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3672.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/01\/17\/les-droits-fondamentaux-des-migrant-e-s-doivent-tre-respects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Les droits fondamentaux des migrant.e.s doivent \u00eatre respect\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=221"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/221\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}