{"id":23308,"date":"2023-01-10T12:14:14","date_gmt":"2023-01-10T11:14:14","guid":{"rendered":"http:\/\/snuipp86.fr\/?p=23308"},"modified":"2023-01-10T12:20:27","modified_gmt":"2023-01-10T11:20:27","slug":"cheques-vacances-2023","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/","title":{"rendered":"Ch\u00e8ques Vacances 2023"},"content":{"rendered":"<p>J\u2019\u00e9pargne pendant 4 \u00e0 12 mois, je r\u00e9cup\u00e8re une bonification de 10 % \u00e0 30% (cf.\u00a0<a href=\"https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/documents\/pdf\/baremes.pdf\">bar\u00e8me<\/a>), voire 35 % pour les moins de 30 ans, subventionn\u00e9e par l\u2019\u00c9tat. Les agents en activit\u00e9 et en situation de handicap b\u00e9n\u00e9ficient d\u2019une bonification suppl\u00e9mentaire.<\/p>\n<p>Les ch\u00e8ques vacances sont valables 2 ans \u00e0 partir de la date d\u2019\u00e9mission et peuvent \u00eatre \u00e9chang\u00e9s jusqu\u2019\u00e0 3 mois apr\u00e8s la fin de validit\u00e9.<\/p>\n<p>Ils sont utilisables tout au long de l\u2019ann\u00e9e pour les vacances et loisirs :<a href=\"https:\/\/guide.ancv.com\/\">\u00a0https:\/\/guide.ancv.com\/<\/a><\/p>\n<p><b>Vite, j\u2019en profite !<\/b>\u00a0<a href=\"https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/faq_constituer\">https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/faq_constituer<\/a><\/p>\n<p><b>&gt;&gt;<\/b>\u00a0<i>Pour remplir au mieux son dossier<\/i>\u00a0: les pr\u00e9l\u00e8vements d\u00e9butent dans un d\u00e9lai approximatif de 6 semaines apr\u00e8s la validation du dossier et l\u2019envoi postal en recommand\u00e9 des ch\u00e8ques vacances se fait dans un d\u00e9lai approximatif de 6 semaines apr\u00e8s la derni\u00e8re \u00e9ch\u00e9ance.<\/p>\n<p>Mode d\u2019emploi :<a href=\"https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/documents\/pdf\/cheque_mode_emploi.pdf\">\u00a0https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/documents\/pdf\/cheque_mode_emploi.pdf<\/a><\/p>\n<p>Bar\u00e8mes \/ \u00e9ligibilit\u00e9 :<a href=\"https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/documents\/pdf\/baremes.pdf\">\u00a0https:\/\/www.fonctionpublique-chequesvacances.fr\/cv\/web\/documents\/pdf\/baremes.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019\u00e9pargne pendant 4 \u00e0 12 mois, je r\u00e9cup\u00e8re une bonification de 10 % \u00e0 30% (cf.\u00a0bar\u00e8me), voire 35 % pour les moins de 30 ans, subventionn\u00e9e par l\u2019\u00c9tat. Les agents en activit\u00e9 et en situation de handicap b\u00e9n\u00e9ficient d\u2019une bonification suppl\u00e9mentaire. Les ch\u00e8ques vacances sont valables 2 ans \u00e0 partir de la date d\u2019\u00e9mission et peuvent [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,62],"tags":[54],"class_list":["post-23308","post","type-post","status-publish","format-standard","hentry","category-a-la-une","category-action-sociale","tag-action-sociale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ch\u00e8ques Vacances 2023 - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ch\u00e8ques Vacances 2023 - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"J\u2019\u00e9pargne pendant 4 \u00e0 12 mois, je r\u00e9cup\u00e8re une bonification de 10 % \u00e0 30% (cf.\u00a0bar\u00e8me), voire 35 % pour les moins de 30 ans, subventionn\u00e9e par l\u2019\u00c9tat. Les agents en activit\u00e9 et en situation de handicap b\u00e9n\u00e9ficient d\u2019une bonification suppl\u00e9mentaire. Les ch\u00e8ques vacances sont valables 2 ans \u00e0 partir de la date d\u2019\u00e9mission et peuvent [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-10T11:14:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-10T11:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/snuipp86.fr\/wp-content\/uploads\/2020\/09\/acv.png\" \/>\n\t<meta property=\"og:image:width\" content=\"355\" \/>\n\t<meta property=\"og:image:height\" content=\"242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilie Bordes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emilie Bordes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/\",\"name\":\"Ch\u00e8ques Vacances 2023 - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"datePublished\":\"2023-01-10T11:14:14+00:00\",\"dateModified\":\"2023-01-10T11:20:27+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/32551eb3043810865742a1acf011001d\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ch\u00e8ques Vacances 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/32551eb3043810865742a1acf011001d\",\"name\":\"Emilie Bordes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/571abcf3c12ab1aaba66450f3ac5c0f8355284f01f7342dd440489ae804a109e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/571abcf3c12ab1aaba66450f3ac5c0f8355284f01f7342dd440489ae804a109e?s=96&d=mm&r=g\",\"caption\":\"Emilie Bordes\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/ebordes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ch\u00e8ques Vacances 2023 - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Ch\u00e8ques Vacances 2023 - FSU-SNUipp 86","og_description":"J\u2019\u00e9pargne pendant 4 \u00e0 12 mois, je r\u00e9cup\u00e8re une bonification de 10 % \u00e0 30% (cf.\u00a0bar\u00e8me), voire 35 % pour les moins de 30 ans, subventionn\u00e9e par l\u2019\u00c9tat. Les agents en activit\u00e9 et en situation de handicap b\u00e9n\u00e9ficient d\u2019une bonification suppl\u00e9mentaire. Les ch\u00e8ques vacances sont valables 2 ans \u00e0 partir de la date d\u2019\u00e9mission et peuvent [&hellip;]","og_url":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2023-01-10T11:14:14+00:00","article_modified_time":"2023-01-10T11:20:27+00:00","og_image":[{"width":355,"height":242,"url":"https:\/\/snuipp86.fr\/wp-content\/uploads\/2020\/09\/acv.png","type":"image\/png"}],"author":"Emilie Bordes","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Emilie Bordes","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/","url":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/","name":"Ch\u00e8ques Vacances 2023 - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"datePublished":"2023-01-10T11:14:14+00:00","dateModified":"2023-01-10T11:20:27+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/32551eb3043810865742a1acf011001d"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2023\/01\/10\/cheques-vacances-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Ch\u00e8ques Vacances 2023"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/32551eb3043810865742a1acf011001d","name":"Emilie Bordes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/571abcf3c12ab1aaba66450f3ac5c0f8355284f01f7342dd440489ae804a109e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/571abcf3c12ab1aaba66450f3ac5c0f8355284f01f7342dd440489ae804a109e?s=96&d=mm&r=g","caption":"Emilie Bordes"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/ebordes\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/23308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=23308"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/23308\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=23308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=23308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=23308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}