{"id":242,"date":"2017-12-22T06:55:35","date_gmt":"2017-12-22T06:55:35","guid":{"rendered":"http:\/\/localhost\/wordpress\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/"},"modified":"2017-12-22T06:55:35","modified_gmt":"2017-12-22T06:55:35","slug":"carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/","title":{"rendered":"Carte scolaire 2018 : 0 poste sur 3880 pour l&rsquo;acad\u00e9mie de Poitiers !"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png\" alt=\"\" align=\"right\" width=\"650\" height=\"674\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">La r\u00e9partition acad\u00e9mie par acad\u00e9mie des postes cr\u00e9\u00e9s pour la rentr\u00e9e 2018 a \u00e9t\u00e9 arr\u00eat\u00e9e. Modul\u00e9e en fonction du nombre de CP \u00e0 d\u00e9doubler en REP et de CE1 en REP+, la dotation de 3 880 postes ne permettra pas de remplir cet objectif qui \u00e0 lui seul en demanderait pr\u00e8s de 6 400. Il faudra donc supprimer des postes ailleurs, et par l\u00e0 m\u00eame d\u00e9grader les conditions d&rsquo;enseignement dans les classes ordinaires.<\/p>\n<p class=\"spip\">La dotation globale est largement insuffisante au regard des priorit\u00e9s nationales qui vont absorber tous les postes :<\/p>\n<p class=\"spip\"> d\u00e9doublement des classes de CP en REP, et son co\u00fbt induit (d\u00e9charges de direction, remplacement) ;<br \/>\n<br \/> d\u00e9doublement des classes de CE1 en REP+ partout o\u00f9 les locaux le permettent.<\/p>\n<p class=\"spip\">Une provision de postes est \u00e9galement pr\u00e9vue pour financer les nouvelles conventions d\u00e9partementales \u00ab ruralit\u00e9 \u00bb (100 ETP) et cr\u00e9er de nouvelles ULIS \u00e9cole (100 ETP).<\/p>\n<p class=\"spip\"><strong class=\"spip\">L&rsquo;Acad\u00e9mie de Poitiers a ainsi une dotation de 0 poste pour un pr\u00e9visionnel de 53 classes \u00e0 d\u00e9doubler<\/strong> ( 32 CP en REP et 21 CE1 en REP + ). Dans le m\u00eame temps, l&rsquo;acad\u00e9mie pr\u00e9voit 1.08% d&rsquo;\u00e9l\u00e8ves en moins pour la rentr\u00e9e 2018 soit environ 1 400 \u00e9l\u00e8ves ( contre -0.56% nationalement soit 32 657 \u00e9l\u00e8ves) .<\/p>\n<p class=\"spip\">Retrouvez le tableau r\u00e9capitulatif des dotations acad\u00e9miques sur ce lien : <a href=\"https:\/\/www.snuipp.fr\/actualites\/posts\/le-snuipp-fsu-devoile-les-dotations-academiques\" class=\"spip_out\">https:\/\/www.snuipp.fr\/actualites\/posts\/le-snuipp-fsu-devoile-les-dotations-academiques<\/a><\/p>\n<dl class='spip_document_3026 spip_documents spip_documents_center' >\n<dt><img src='https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/png\/Academies-Carte_Sco_2018.png' width='520' height='540' alt='PNG - 172 ko' style='height:540px;width:520px;' class=' format_png' \/><\/dt>\n<dt class='spip_doc_titre' style='width:350px;'><strong>Acad\u00e9mies-Carte Sco 2018<\/strong><\/dt>\n<\/dl>\n<p class=\"spip\">Dans 21 acad\u00e9mies, la dotation est en-de\u00e7\u00e0 du nombre estim\u00e9 de postes n\u00e9cessaires pour d\u00e9doubler les classes de CP en REP. On voit mal comment pourrait s&rsquo;amorcer le d\u00e9doublement des classes de CE1 en REP+ dans ces circonstances.<\/p>\n<p class=\"spip\">Le SNUipp-FSU d\u00e9nonce une dotation pour la rentr\u00e9e 2018 qui ent\u00e9rine un red\u00e9ploiement des moyens d\u00e9j\u00e0 existants ainsi qu&rsquo;une d\u00e9gradation des conditions d&rsquo;enseignement et de scolarisation.<\/p>\n<p class=\"spip\"><strong class=\"spip\">Communiqu\u00e9 du SNUipp-FSU <\/strong><\/p>\n<h3 class=\"spip\">R\u00e9partition des postes : des choix qui ne r\u00e9duiront pas les<br \/>\nin\u00e9galit\u00e9s<\/h3>\n<p class=\"spip\">Le budget 2018 adopt\u00e9 par le parlement pr\u00e9voit la cr\u00e9ation de 3 881 postes<br \/>\ndans le primaire \u00e0 la rentr\u00e9e prochaine.<br \/>\nLe minist\u00e8re a fait le choix de les consacrer exclusivement \u00e0 la poursuite du<br \/>\nd\u00e9doublement des classes en CP en REP et CE1 en REP+.<br \/>\nConjugu\u00e9es \u00e0 une faible baisse du nombre d&rsquo;\u00e9l\u00e8ves, ces cr\u00e9ations auraient d\u00fb<br \/>\n\u00eatre l&rsquo;occasion de diminuer les effectifs dans toutes les \u00e9coles o\u00f9 les classes sont<br \/>\nsurcharg\u00e9es, d&rsquo;am\u00e9liorer les remplacements, de d\u00e9velopper le plus de ma\u00eetres, les<br \/>\nRased, la formation des enseignants\u2026<br \/>\nBien que l&rsquo;ensemble des cr\u00e9ations de postes sera affect\u00e9 \u00e0 ce d\u00e9doublement,<br \/>\ncela sera insuffisant car il en faudrait, pr\u00e8s de 6 400. Des centaines de postes de<br \/>\nplus de ma\u00eetres, de Rased, de rempla\u00e7ants, de classe ordinaire\u2026 risquent d&rsquo;\u00eatre<br \/>\nainsi supprim\u00e9s.<br \/>\nSi l&rsquo;abaissement des effectifs en \u00e9ducation prioritaire est encore plus l\u00e9gitime<br \/>\nqu&rsquo;ailleurs, le seul effort fait en direction des CP et CE1 sans les cr\u00e9ations de<br \/>\nmoyens n\u00e9cessaires va se r\u00e9aliser au d\u00e9triment de la r\u00e9ussite de tous les \u00e9l\u00e8ves et<br \/>\nne permet pas de rem\u00e9dier efficacement \u00e0 la difficult\u00e9 scolaire, de travailler<br \/>\nautrement dans les classes, de scolariser des 2 ans\u2026<br \/>\nL&rsquo;\u00e9cole primaire fran\u00e7aise largement sous-investie et marqu\u00e9e par des<br \/>\nin\u00e9galit\u00e9s insupportables doit faire l&rsquo;objet d&rsquo;un engagement financier massif pour<br \/>\nr\u00e9aliser les transformations n\u00e9cessaires, \u00e0 commencer par une baisse des effectifs.<br \/>\nLe budget 2018 ne r\u00e9pondait pas \u00e0 cet enjeu de soci\u00e9t\u00e9. Les choix faits par le<br \/>\nminist\u00e8re y r\u00e9pondent encore moins.<\/p>\n<p class=\"spip\">Paris le 20 d\u00e9cembre 2017<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e9partition acad\u00e9mie par acad\u00e9mie des postes cr\u00e9\u00e9s pour la rentr\u00e9e 2018 a \u00e9t\u00e9 arr\u00eat\u00e9e. Modul\u00e9e en fonction du nombre de CP \u00e0 d\u00e9doubler en REP et de CE1 en REP+, la dotation de 3 880 postes ne permettra pas de remplir cet objectif qui \u00e0 lui seul en demanderait pr\u00e8s de 6 400. Il faudra donc supprimer des postes ailleurs, et par l\u00e0 m\u00eame d\u00e9grader les conditions d&rsquo;enseignement dans les classes ordinaires. <br \/>La dotation globale est largement insuffisante au regard des priorit\u00e9s nationales qui (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique159\" rel=\"directory\">Carte scolaire<\/a><br \/>\n\/<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?mot293\" rel=\"tag\">Carte scolaire<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-242","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carte scolaire 2018 : 0 poste sur 3880 pour l&#039;acad\u00e9mie de Poitiers ! - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carte scolaire 2018 : 0 poste sur 3880 pour l&#039;acad\u00e9mie de Poitiers ! - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"La r\u00e9partition acad\u00e9mie par acad\u00e9mie des postes cr\u00e9\u00e9s pour la rentr\u00e9e 2018 a \u00e9t\u00e9 arr\u00eat\u00e9e. Modul\u00e9e en fonction du nombre de CP \u00e0 d\u00e9doubler en REP et de CE1 en REP+, la dotation de 3 880 postes ne permettra pas de remplir cet objectif qui \u00e0 lui seul en demanderait pr\u00e8s de 6 400. Il faudra donc supprimer des postes ailleurs, et par l\u00e0 m\u00eame d\u00e9grader les conditions d&#039;enseignement dans les classes ordinaires. La dotation globale est largement insuffisante au regard des priorit\u00e9s nationales qui (...) - Carte scolaire \/ Carte scolaire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-22T06:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/\",\"name\":\"Carte scolaire 2018 : 0 poste sur 3880 pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png\",\"datePublished\":\"2017-12-22T06:55:35+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carte scolaire 2018 : 0 poste sur 3880 pour l&#8217;acad\u00e9mie de Poitiers !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carte scolaire 2018 : 0 poste sur 3880 pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/","og_locale":"fr_FR","og_type":"article","og_title":"Carte scolaire 2018 : 0 poste sur 3880 pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86","og_description":"La r\u00e9partition acad\u00e9mie par acad\u00e9mie des postes cr\u00e9\u00e9s pour la rentr\u00e9e 2018 a \u00e9t\u00e9 arr\u00eat\u00e9e. Modul\u00e9e en fonction du nombre de CP \u00e0 d\u00e9doubler en REP et de CE1 en REP+, la dotation de 3 880 postes ne permettra pas de remplir cet objectif qui \u00e0 lui seul en demanderait pr\u00e8s de 6 400. Il faudra donc supprimer des postes ailleurs, et par l\u00e0 m\u00eame d\u00e9grader les conditions d'enseignement dans les classes ordinaires. La dotation globale est largement insuffisante au regard des priorit\u00e9s nationales qui (...) - Carte scolaire \/ Carte scolaire","og_url":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2017-12-22T06:55:35+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/","url":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/","name":"Carte scolaire 2018 : 0 poste sur 3880 pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png","datePublished":"2017-12-22T06:55:35+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton3606.png"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2017\/12\/22\/carte-scolaire-2018-0-poste-sur-3880-pour-lacadmie-de-poitiers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Carte scolaire 2018 : 0 poste sur 3880 pour l&#8217;acad\u00e9mie de Poitiers !"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=242"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/242\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}