{"id":72,"date":"2019-01-21T15:18:04","date_gmt":"2019-01-21T15:18:04","guid":{"rendered":"http:\/\/localhost\/wordpress\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/"},"modified":"2019-01-21T15:18:04","modified_gmt":"2019-01-21T15:18:04","slug":"groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/","title":{"rendered":"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png\" alt=\"\" align=\"right\" width=\"280\" height=\"305\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">Un groupe de travail s&rsquo;est tenu le 18 janvier 2019 afin de travailler sur le r\u00e8glement type des \u00e9coles maternelles et \u00e9l\u00e9mentaires de la Vienne (<a href=\"https:\/\/www.intra.ac-poitiers.fr\/mes-rubriques\/reglement-type-departemental-des-ecoles-de-la-vienne-255915.kjsp?RH=1192696847494\" class=\"spip_out\">voir celui actualis\u00e9 de novembre 2018<\/a> ) . Ce r\u00e8glement type d\u00e9partemental sert \u00e0 d\u00e9finir les modalit\u00e9s de fonctionnement des \u00e9coles publiques dans le cadre des dispositions l\u00e9gislatives et r\u00e9glementaires organisant au niveau national l&rsquo;enseignement pr\u00e9-\u00e9l\u00e9mentaire et \u00e9l\u00e9mentaire, et fournit un cadre et des orientations pour la r\u00e9daction du r\u00e8glement int\u00e9rieur de chaque \u00e9cole.<\/p>\n<p class=\"spip\">Ce groupe de travail s&rsquo;inscrit dans le cadre du Conseil D\u00e9partemental de l&rsquo;Education Nationale (CDEN) et l&rsquo;ensemble des repr\u00e9sentant-es des personnels et des associations de parents \u200b\u00e9tait invit\u00e9. Le SNUipp si\u00e8ge au sein de la d\u00e9l\u00e9gation FSU-CGT.<\/p>\n<p class=\"spip\">\u00c9taient pr\u00e9sent-es : M. Artaud (IENA), M. Bonnet (IEN Poitiers Est), M. Brouleau (CPD Eps), Mme. Briand (DEE) Mme Lemonnier (infirmi\u00e8re) 2 coll\u00e8gues directeurs-trices (Nieuil l&rsquo;Espoir \u00e9l\u00e9m, Poitiers Allard-Ferry \u00e9l\u00e9m),<strong class=\"spip\"> 3 SNUipp-FSU<\/strong>, 2 UNSA et 1 SNALC.<\/p>\n<p class=\"spip\">Ce r\u00e8glement \u00e9tant construit \u00e0 partir de textes r\u00e9glementaires nationaux, nos demandes n&rsquo;ont, pour la plupart, pas pu \u00eatre prises en compte. Lors de ces \u00e9changes, le SNUipp-FSU a par exemple demand\u00e9 :<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Scolarisation des &#8211; de 3 ans : d\u00e9termination des capacit\u00e9s d&rsquo;accueil et demande de consultation des \u00e9quipes, demandes de propret\u00e9 \u00e0 l&rsquo;entr\u00e9e dans l&rsquo;\u00e9cole, d\u00e9fense du caract\u00e8re prioritaire de ce type de dispositif en milieu d\u00e9favoris\u00e9 rural et\/ou urbain &#8230;<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Scolarisation des enfants du voyage : d\u00e9termination des capacit\u00e9s d&rsquo;accueil<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> PPMS : demande de ma suppression de la responsabilit\u00e9 du directeur-trice<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> APC : demande de suppression de l&rsquo;obligation de les mettre en \u0153uvre<\/p>\n<p class=\"spip\"><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/cache-vignettes\/L8xH11\/puce-68c92.gif\" width='8' height='11' alt=\"-\" style='height:11px;width:8px;' class='' \/> Sortie scolaire : intervention sur l&rsquo;accompagnement des \u00e9l\u00e8ves en situation de handicap : difficult\u00e9s li\u00e9es au statut d&#8217;emploi de l&rsquo;AVS.<\/p>\n<p class=\"spip\">Bien que nous appuyant sur des situations concr\u00e8tes dans le d\u00e9partement, l&rsquo;administration ne nous a oppos\u00e9 que des articles du code de l&rsquo;\u00e9ducation afin de rester le plus large possible, malgr\u00e9 notre volont\u00e9 d&rsquo;inscrire plus de pr\u00e9cisions dans ce r\u00e8glement afin de prot\u00e9ger les coll\u00e8gues. Des d\u00e9bats ont eu lieu sur les situations de garde altern\u00e9e et de proc\u00e9dure de radiation, sur la f\u00e9minisation du texte et de l&rsquo;\u00e9criture inclusive, sur la charge de travail des directeurs-trices et le manque de moyens pour y arriver &#8230; Enfin, un certain nombre d&rsquo;ajustements sur le texte ont \u00e9t\u00e9 act\u00e9s : partie sur le t\u00e9l\u00e9phone portable \u00e0 l&rsquo;\u00e9cole, mot \u00a0\u00bb r\u00e9primande \u00a0\u00bb enlev\u00e9 et remplac\u00e9 par \u00a0\u00bb sanction \u00ab\u00a0, ajout de vapotage \u00e0 l&rsquo;interdiction de fumer &#8230; etc.<\/p>\n<p class=\"spip\">Pour conclure, le travail effectu\u00e9 ce jour reste soumis \u00e0 validation du DASEN et du CDEN, et devra \u00eatre reconduit d&rsquo;ici la fin de l&rsquo;ann\u00e9e afin d&rsquo;int\u00e9grer toutes les modifications li\u00e9es \u00e0 la loi sur la scolarisation obligatoire \u00e0 3 ans qui sera vot\u00e9e au printemps prochain.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un groupe de travail s&rsquo;est tenu le 18 janvier 2019 afin de travailler sur le r\u00e8glement type des \u00e9coles maternelles et \u00e9l\u00e9mentaires de la Vienne (voir celui actualis\u00e9 de novembre 2018 ) . Ce r\u00e8glement type d\u00e9partemental sert \u00e0 d\u00e9finir les modalit\u00e9s de fonctionnement des \u00e9coles publiques dans le cadre des dispositions l\u00e9gislatives et r\u00e9glementaires organisant au niveau national l&rsquo;enseignement pr\u00e9-\u00e9l\u00e9mentaire et \u00e9l\u00e9mentaire, et fournit un cadre et des orientations pour la r\u00e9daction du (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique41\" rel=\"directory\">CDEN<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-72","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Un groupe de travail s&#039;est tenu le 18 janvier 2019 afin de travailler sur le r\u00e8glement type des \u00e9coles maternelles et \u00e9l\u00e9mentaires de la Vienne (voir celui actualis\u00e9 de novembre 2018 ) . Ce r\u00e8glement type d\u00e9partemental sert \u00e0 d\u00e9finir les modalit\u00e9s de fonctionnement des \u00e9coles publiques dans le cadre des dispositions l\u00e9gislatives et r\u00e9glementaires organisant au niveau national l&#039;enseignement pr\u00e9-\u00e9l\u00e9mentaire et \u00e9l\u00e9mentaire, et fournit un cadre et des orientations pour la r\u00e9daction du (...) - CDEN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-21T15:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/\",\"name\":\"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png\",\"datePublished\":\"2019-01-21T15:18:04+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/","og_locale":"fr_FR","og_type":"article","og_title":"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier - FSU-SNUipp 86","og_description":"Un groupe de travail s'est tenu le 18 janvier 2019 afin de travailler sur le r\u00e8glement type des \u00e9coles maternelles et \u00e9l\u00e9mentaires de la Vienne (voir celui actualis\u00e9 de novembre 2018 ) . Ce r\u00e8glement type d\u00e9partemental sert \u00e0 d\u00e9finir les modalit\u00e9s de fonctionnement des \u00e9coles publiques dans le cadre des dispositions l\u00e9gislatives et r\u00e9glementaires organisant au niveau national l'enseignement pr\u00e9-\u00e9l\u00e9mentaire et \u00e9l\u00e9mentaire, et fournit un cadre et des orientations pour la r\u00e9daction du (...) - CDEN","og_url":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2019-01-21T15:18:04+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/","url":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/","name":"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png","datePublished":"2019-01-21T15:18:04+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4250.png"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2019\/01\/21\/groupe-de-travail-sur-le-rglement-type-des-coles-de-la-vienne-du-18-janvier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Groupe de travail sur le r\u00e8glement type des \u00e9coles de la Vienne du 18 janvier"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/72\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=72"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=72"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}