{"id":80,"date":"2018-12-19T16:55:33","date_gmt":"2018-12-19T16:55:33","guid":{"rendered":"http:\/\/localhost\/wordpress\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/"},"modified":"2018-12-19T16:55:33","modified_gmt":"2018-12-19T16:55:33","slug":"rentre-2019-aucun-poste-pour-lacadmie-de-poitiers","status":"publish","type":"post","link":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/","title":{"rendered":"Rentr\u00e9e 2019 : aucun poste pour l&rsquo;acad\u00e9mie de Poitiers !"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg\" alt=\"\" align=\"right\" width=\"550\" height=\"240\" class=\"spip_logos\" \/><\/p>\n<div class='rss_texte'>\n<p class=\"spip\">Le minist\u00e8re de l&rsquo;\u00c9ducation Nationale a communiqu\u00e9 ce mercredi la r\u00e9partition acad\u00e9mie par acad\u00e9mie des 2325 postes cr\u00e9\u00e9s pour la rentr\u00e9e 2019 dans le 1er degr\u00e9.<br \/>\n<strong class=\"spip\">Pour l&rsquo;acad\u00e9mie de Poitiers, c&rsquo;est une dotation de 0 poste !<\/strong><\/p>\n<p class=\"spip\">Pourtant, des besoins existent. Le remplacement dans notre d\u00e9partement met \u00e0 mal les \u00e9coles, les \u00e9quipes et les \u00e9l\u00e8ves : la semaine derni\u00e8re, il aurait fallu une cinquantaine de rempla\u00e7ants suppl\u00e9mentaires devant les \u00e9l\u00e8ves. Nous vous rappelons de faire remonter \u00e0 votre IEN toute situation de non-remplacement et de nous en informer (voir ici).<br \/>\nIl manque \u00e9galement des postes pour assurer l&rsquo;accompagnement des \u00e9l\u00e8ves handicap\u00e9s ou en difficult\u00e9 scolaire.<br \/>\nEnfin, des cr\u00e9ations de postes sont n\u00e9cessaires avec les d\u00e9doublements des CE1 en \u00e9ducation prioritaire, 16 postes dans la Vienne devront \u00eatre trouv\u00e9s pour effectuer ces ouvertures.<\/p>\n<p class=\"spip\">Autant de moyens qu&rsquo;il faudra donc, comme l&rsquo;an pass\u00e9, chercher ailleurs. Si on se fie aux choix de l&rsquo;ann\u00e9e derni\u00e8re, cela impliquera de fermer d\u00e9finitivement le dispositif \u00ab Plus de ma\u00eetres que de classes \u00bb, fermer aussi dans le rural, en maternelle, tout en chargeant encore un peu plus les autres classes.<\/p>\n<p class=\"spip\">Le SNUipp-FSU 86 incite l&rsquo;ensemble des enseignant-es, des parents, des \u00e9lu-es, \u00e0 se mobiliser pour d\u00e9fendre un service public d&rsquo;\u00e9ducation de qualit\u00e9 et de proximit\u00e9.<\/p>\n<p class=\"spip\">D&rsquo;ores et d\u00e9j\u00e0, remplissez l&rsquo;enqu\u00eate carte scolaire du SNUipp-FSU : https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/doc\/Enquete_carte_scolaire_2019.doc<\/p>\n<p class=\"spip\">Retrouvez les dotations de toutes les acad\u00e9mies sur ce lien : http:\/\/86.snuipp.fr\/spip.php ?article4218<\/p>\n<p class=\"spip\">Prochaines \u00e9tapes :<\/p>\n<p class=\"spip\">dotation d\u00e9partementale : le 22 janvier en CTA ouvertures et fermetures pour la rentr\u00e9e 2019 : 4 f\u00e9vrier en CTSD<\/p>\n<p class=\"spip\">N&rsquo;attendez pas, revnoyez nous d&rsquo;ores et d\u00e9j\u00e0 les chiffres de votre \u00e9cole en remplissant cette enqu\u00eate carte scolaire : <a href=\"https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/doc\/Enquete_carte_scolaire_2019.doc\" class=\"spip_out\">https:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/doc\/Enquete_carte_scolaire_2019.doc<\/a><br \/>\nLes d\u00e9cisions de carte scolaire seront prises au CTSD du 4 f\u00e9vrier.<\/p>\n<p class=\"spip\">Retrouvez ci-dessous la r\u00e9partition nationale des postes<\/p>\n<table class=\"spip\">\n<tbody>\n<tr class=\"row_even\">\n<td> Acad\u00e9mies <\/td>\n<td> <strong class=\"spip\">Mesures de rentr\u00e9e 2019<\/strong> <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> AIX-MARSEILLE <\/td>\n<td> 110 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> AMIENS <\/td>\n<td> 15 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> BESAN\u00c7ON <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> BORDEAUX <\/td>\n<td> 94 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> CAEN <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> CLERMONT-FERRAND <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> CORSE <\/td>\n<td> 48 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> CR\u00c9TEIL <\/td>\n<td> 502 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> DIJON <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> GRENOBLE <\/td>\n<td> 31 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> GUADELOUPE <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> GUYANE <\/td>\n<td> 150 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> LILLE <\/td>\n<td> 44 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> LIMOGES <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> LYON <\/td>\n<td> 175 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> MARTINIQUE <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> MONTPELLIER <\/td>\n<td> 49 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> NANCY-METZ <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> NANTES <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> NICE <\/td>\n<td> 38 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> ORL\u00c9ANS-TOURS <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> PARIS <\/td>\n<td> 40 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> <strong class=\"spip\">POITIERS<\/strong> <\/td>\n<td> <strong class=\"spip\">0<\/strong> <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> REIMS <\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> RENNES<\/td>\n<td> 0 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> R\u00c9UNION <\/td>\n<td> 122 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> ROUEN <\/td>\n<td> 34 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> STRASBOURG <\/td>\n<td> 56 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> TOULOUSE <\/td>\n<td> 55 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> VERSAILLES <\/td>\n<td> 462 <\/td>\n<\/tr>\n<tr class=\"row_odd\">\n<td> MAYOTTE <\/td>\n<td> 150 <\/td>\n<\/tr>\n<tr class=\"row_even\">\n<td> <strong class=\"spip\">TOTAL<\/strong> <\/td>\n<td> <strong class=\"spip\">2175*<\/strong> <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"spip\"><strong class=\"spip\">*<\/strong>R\u00e9serve : <strong class=\"spip\">+ 150 ETP<\/strong> (\u00e9quivalents temps plein)<br \/>\n<br \/>Pour une dotation totale de <strong class=\"spip\">2325 postes<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re de l&rsquo;\u00c9ducation Nationale a communiqu\u00e9 ce mercredi la r\u00e9partition acad\u00e9mie par acad\u00e9mie des 2325 postes cr\u00e9\u00e9s pour la rentr\u00e9e 2019 dans le 1er degr\u00e9. Pour l&rsquo;acad\u00e9mie de Poitiers, c&rsquo;est une dotation de 0 poste ! <br \/>Pourtant, des besoins existent. Le remplacement dans notre d\u00e9partement met \u00e0 mal les \u00e9coles, les \u00e9quipes et les \u00e9l\u00e8ves : la semaine derni\u00e8re, il aurait fallu une cinquantaine de rempla\u00e7ants suppl\u00e9mentaires devant les \u00e9l\u00e8ves. Nous vous rappelons de faire remonter \u00e0 (&#8230;)<br \/>\n&#8211;<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?rubrique159\" rel=\"directory\">Carte scolaire<\/a><br \/>\n\/<br \/>\n<a href=\"http:\/\/86.snuipp.fr\/spip.php?mot293\" rel=\"tag\">Carte scolaire<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-80","post","type-post","status-publish","format-standard","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rentr\u00e9e 2019 : aucun poste pour l&#039;acad\u00e9mie de Poitiers ! - FSU-SNUipp 86<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rentr\u00e9e 2019 : aucun poste pour l&#039;acad\u00e9mie de Poitiers ! - FSU-SNUipp 86\" \/>\n<meta property=\"og:description\" content=\"Le minist\u00e8re de l&#039;\u00c9ducation Nationale a communiqu\u00e9 ce mercredi la r\u00e9partition acad\u00e9mie par acad\u00e9mie des 2325 postes cr\u00e9\u00e9s pour la rentr\u00e9e 2019 dans le 1er degr\u00e9. Pour l&#039;acad\u00e9mie de Poitiers, c&#039;est une dotation de 0 poste ! Pourtant, des besoins existent. Le remplacement dans notre d\u00e9partement met \u00e0 mal les \u00e9coles, les \u00e9quipes et les \u00e9l\u00e8ves : la semaine derni\u00e8re, il aurait fallu une cinquantaine de rempla\u00e7ants suppl\u00e9mentaires devant les \u00e9l\u00e8ves. Nous vous rappelons de faire remonter \u00e0 (...) - Carte scolaire \/ Carte scolaire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/\" \/>\n<meta property=\"og:site_name\" content=\"FSU-SNUipp 86\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T16:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg\" \/>\n<meta name=\"author\" content=\"WP86Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP86Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/\",\"url\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/\",\"name\":\"Rentr\u00e9e 2019 : aucun poste pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86\",\"isPartOf\":{\"@id\":\"https:\/\/snuipp86.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg\",\"datePublished\":\"2018-12-19T16:55:33+00:00\",\"author\":{\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#primaryimage\",\"url\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg\",\"contentUrl\":\"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/snuipp86.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rentr\u00e9e 2019 : aucun poste pour l&#8217;acad\u00e9mie de Poitiers !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/snuipp86.fr\/#website\",\"url\":\"https:\/\/snuipp86.fr\/\",\"name\":\"FSU-SNUipp 86\",\"description\":\"Des id\u00e9es qui font l&#039;\u00e9cole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/snuipp86.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2\",\"name\":\"WP86Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g\",\"caption\":\"WP86Admin\"},\"url\":\"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rentr\u00e9e 2019 : aucun poste pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/","og_locale":"fr_FR","og_type":"article","og_title":"Rentr\u00e9e 2019 : aucun poste pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86","og_description":"Le minist\u00e8re de l'\u00c9ducation Nationale a communiqu\u00e9 ce mercredi la r\u00e9partition acad\u00e9mie par acad\u00e9mie des 2325 postes cr\u00e9\u00e9s pour la rentr\u00e9e 2019 dans le 1er degr\u00e9. Pour l'acad\u00e9mie de Poitiers, c'est une dotation de 0 poste ! Pourtant, des besoins existent. Le remplacement dans notre d\u00e9partement met \u00e0 mal les \u00e9coles, les \u00e9quipes et les \u00e9l\u00e8ves : la semaine derni\u00e8re, il aurait fallu une cinquantaine de rempla\u00e7ants suppl\u00e9mentaires devant les \u00e9l\u00e8ves. Nous vous rappelons de faire remonter \u00e0 (...) - Carte scolaire \/ Carte scolaire","og_url":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/","og_site_name":"FSU-SNUipp 86","article_published_time":"2018-12-19T16:55:33+00:00","og_image":[{"url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg","type":"","width":"","height":""}],"author":"WP86Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"WP86Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/","url":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/","name":"Rentr\u00e9e 2019 : aucun poste pour l'acad\u00e9mie de Poitiers ! - FSU-SNUipp 86","isPartOf":{"@id":"https:\/\/snuipp86.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#primaryimage"},"image":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#primaryimage"},"thumbnailUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg","datePublished":"2018-12-19T16:55:33+00:00","author":{"@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2"},"breadcrumb":{"@id":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#primaryimage","url":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg","contentUrl":"http:\/\/snuipp86.fr\/wp-content\/spip\/IMG\/arton4218.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/snuipp86.fr\/index.php\/2018\/12\/19\/rentre-2019-aucun-poste-pour-lacadmie-de-poitiers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/snuipp86.fr\/"},{"@type":"ListItem","position":2,"name":"Rentr\u00e9e 2019 : aucun poste pour l&#8217;acad\u00e9mie de Poitiers !"}]},{"@type":"WebSite","@id":"https:\/\/snuipp86.fr\/#website","url":"https:\/\/snuipp86.fr\/","name":"FSU-SNUipp 86","description":"Des id\u00e9es qui font l&#039;\u00e9cole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snuipp86.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/901b28b9ae1c7a63a6a940102e52a7a2","name":"WP86Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/snuipp86.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0099845c7ec05dc10d777d8ab4f5142c5ba316283821af2459738ad469a37a1a?s=96&d=mm&r=g","caption":"WP86Admin"},"url":"https:\/\/snuipp86.fr\/index.php\/author\/wp86admin\/"}]}},"_links":{"self":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":0,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/posts\/80\/revisions"}],"wp:attachment":[{"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/media?parent=80"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/categories?post=80"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snuipp86.fr\/index.php\/wp-json\/wp\/v2\/tags?post=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}